{"id":64607,"date":"2020-09-15T11:54:17","date_gmt":"2020-09-15T11:54:17","guid":{"rendered":"https:\/\/solplanet.net\/installer-area\/"},"modified":"2024-03-06T03:25:22","modified_gmt":"2024-03-06T03:25:22","slug":"area-do-instalador","status":"publish","type":"page","link":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador","title":{"rendered":"Installer Area"},"content":{"rendered":"<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/FOTO-Featured-HomePage.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--big jumbotron__heading\">\n\tA Solplanet facilita-lhe a vida<\/h1><p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tF\u00e1cil de instalar, fi\u00e1vel e f\u00e1cil de utilizar<\/p>\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--100 wrapper__spacing-bottom-large--180\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--default block-columns__vertical-spacing-large--default\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\tA Solplanet facilita-lhe a vida<\/h2>\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--7 block-column__width-tablet--12 block-column__offset-large--1 block-column__offset-tablet--0 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tA Solplanet facilita-lhe a vida. Os nossos produtos s\u00e3o f\u00e1ceis de instalar, fi\u00e1veis e<br>f\u00e1ceis de utilizar.<br><br>Continuamos a tornar os nossos produtos, aplica\u00e7\u00f5es e informa\u00e7\u00f5es mais r\u00e1pidos e f\u00e1ceis de utilizar, assegurando simultaneamente um desempenho e uma fiabilidade de topo.<br><br>Desta forma, podemos cumprir a nossa miss\u00e3o de levar a energia solar a todos.\u00a0<\/p>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--70 wrapper__spacing-bottom-large--60\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"solplus\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--default block-columns__vertical-spacing-large--default\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/08\/SolplusdetachedLogo-3.png\" class=\"image block-image__image\" \/>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--7 block-column__width-tablet--12 block-column__offset-large--1 block-column__offset-tablet--0 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSolPlus: o novo programa de fideliza\u00e7\u00e3o da Solplanet!<br><br>Acumule S+ Points ao comprar produtos Solplanet e obtenha benef\u00edcios exclusivos: produtos gratuitos, forma\u00e7\u00e3o especial e muito mais.<br>Aumente o seu n\u00edvel de ades\u00e3o e beneficie de ofertas exclusivas!<br><br>Quer saber mais? <a href=\"https:\/\/www.solplus.net\/pt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui<\/a><br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/www.solplus.net\/pt\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Site SolPlus\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tSite SolPlus\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--60 wrapper__spacing-bottom-large--60\" id=\"video-center\">\n\t<div class=\"wrapper__anchor\" id=\"video-center\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default block-heading__heading\">\n\tCentro de v\u00eddeos<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--90 wrapper__spacing-bottom-large--100\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"videos\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div\n\tclass=\"block-carousel js-block-carousel swiper-container block-carousel__pagination-type-under\"\n\tdata-swiper-loop=\"1\"\n\tdata-show-items=\"2\"\n>\n\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/12\/SOLPLANET-SOL-APOLLO-Cable-version-.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSOL APOLLO EV Charger<br>(Cable version)<br>Installation video<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f128e77e\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f128e77e\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f128e77e-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/bHOYEjAViJk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/12\/SOLPLANET-SOL-APOLLO-Socket-version-.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSOL APOLLO EV Charger<br>(Socket version)<br>Installation video<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f128ed20\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f128ed20\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f128ed20-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/ySozPINYQXg?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Vaconn-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f128f243\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f128f243\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f128f243-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/t15zxnm288Q?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Phoenix-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f128f769\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f128f769\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f128f769-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/iDiP44LgbYw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10k-S-Vaconn-DC-terminal-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f128fcd2\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f128fcd2\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f128fcd2-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/TJj4APZDKEA?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10K-S-PhoenixDCTerminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f1290299\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f1290299\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f1290299-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/z0mbp5Sblhc?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/one-phase-installation-2.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tInstala\u00e7\u00e3o monof\u00e1sica<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f129089b\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f129089b\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f129089b-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/EaUn9kaeC50?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/three-phase-installation-2-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tInstala\u00e7\u00e3o trif\u00e1sica<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f1290e29\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f1290e29\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f1290e29-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/6GPw17R6dWU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW-3-5000-H-S-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW3000 5000 H-S installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f1291394\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f1291394\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f1291394-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Aq8Erlfe9c0?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW8-20K-LT-G2-Thumbnail-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW8K 20K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f12918f5\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f12918f5\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f12918f5-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/\/3BVaGCqpBUk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW30-50K-LT-G2-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW30K 50K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f1291f02\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f1291f02\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f1291f02-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Y3y_DifPydU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/glenn-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tO Glen instalou um de olhos vendados<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f12926fd\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f12926fd\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f12926fd-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/0b9owCCXDoo?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2021\/01\/Glen-ASW-T-Series.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tUnboxing of<br>ASW T Series<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841067706a574f1292dbe\" aria-label=\"Reproduzir v\u00eddeo\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841067706a574f1292dbe\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"Fechar\" aria-label=\"Fechar modo\" data-micromodal-close=\"true\">\n\t\t\tFechar\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841067706a574f1292dbe-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--twentyone-nine jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/srgLj0Gvf-M?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<\/div>\n\n\t<div class=\"carousel-navigation carousel-navigation__theme--default block-carousel__carousel-navigation\">\n\t<div class=\"carousel-navigation__item carousel-navigation__item--prev js-block-carousel-prev-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M1 20L21 1M21 39L1 20\" \/><\/g><\/svg>\n\t<\/div>\n\t<div class=\"carousel-navigation__item carousel-navigation__item--next js-block-carousel-next-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M21 20L1 1M1 39l20-19\" \/><\/g><\/svg>\n\t<\/div>\n<\/div><div class=\"carousel-pagination js-block-carousel-pagination carousel-pagination__theme--dark block-carousel__carousel-pagination\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--sand wrapper__spacing-top-large--40 wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"downloads\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-documents\">\n\t\t\t<div class=\"block-documents__intro\">\n\t\t\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-documents__heading heading__color--is-gradient\">\n\tCentro de transfer\u00eancias<\/h2>\t\t<\/div>\n\t\n\t<div class=\"documents js-documents\">\n\t<div class=\"documents__filter documents-filter js-documents-placeholder\">\n\t\t<ul class=\"111  documents-filter__list js-documents-list\" data-index=\"0\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"784\" data-type=\"term\">\n\t\t\t\tFicha t\u00e9cnica\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"789\" data-type=\"term\">\n\t\t\t\tInstru\u00e7\u00f5es de instala\u00e7\u00e3o\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"793\" data-type=\"term\">\n\t\t\t\tCertificado\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"782\" data-type=\"term\">\n\t\t\t\tSoftware\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"786\" data-type=\"term\">\n\t\t\t\tFolheto do produto\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul><ul class=\"111  documents-filter__list js-documents-list\" data-index=\"1\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"64913\" data-type=\"single\">\n\t\t\t\tProduct brochure\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul>\t<\/div>\n\t<div class=\"documents__single js-documents-details\">\n\t\t<div class=\"documents-single\">\n\t\t\t<div class=\"documents-single__title\">\n\t\t\tTransferir\t\t<\/div>\n\t\n\t<div class=\"documents-single__accordion js-accordion-downloads\">\n\t\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-downloads-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-downloads-trigger gtm_question_pt-pt\" aria-label=\"Folheto do produto\">\n\t\tFolheto do produto\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-downloads-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<ul class=\"documents-details\">\n\t\t\t<li class=\"documents-details__item\">\n\t\t\t<a class=\"documents-details__link\" href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Global-Brochure-EU-EN_1023_web-1.pdf\" download>\n\n\t\t\t\t<div class=\"documents-details__title\">\n\t\t\t\t\tSolplanet Product Brochure \t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"documents-details__version\">\n\t\t\t\t\tNov 2023\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"documents-details__language\">\n\t\t\t\t\t\tIngl\u00eas\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"documents-details__action\">\n\t\t\t\t\tpdf\t\t\t\t\t<svg class=\"documents-details__action-icon\" width=\"29\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M28.932 29.619l-.012.024a.661.661 0 01-.513.342l-.02.002-.049.002H.662a.667.667 0 01-.28-.062l-.012-.006a.66.66 0 01-.368-.544L0 29.327v-8.421a.662.662 0 011.321-.05l.002.05v7.759h26.353v-7.759a.662.662 0 011.322-.05l.002.05v8.421l-.004.049-.004.054a.657.657 0 01-.053.176l-.007.013zM14.5 0c.349 0 .635.27.66.612l.002.05-.001 20.062 6.783-6.782a.662.662 0 01.974.894l-.038.042-7.912 7.912-.01.008a.665.665 0 01-.058.05l.068-.058a.665.665 0 01-.172.124l-.01.004a.657.657 0 01-.286.065h-.017c-.011 0-.023 0-.034-.002l.051.002a.665.665 0 01-.292-.067l-.004-.002-.021-.011a.657.657 0 01-.09-.06l-.019-.015-.017-.015a.665.665 0 01-.008-.007L6.12 14.878a.662.662 0 01.894-.974l.042.038 6.782 6.782V.662c0-.366.297-.662.662-.662z\" fill=\"#555\" fill-rule=\"nonzero\" \/><\/svg>\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\t\t<\/li>\n          \t<\/ul>\t\t<\/div>\n\t<\/section>\n<\/div>\t<\/div>\n<\/div>\t<\/div>\n\n\t<div class=\"loader loader--use-overlay documents__loader\">\n\t<div class=\"loader__load\">\n\t\t<div class=\"loader__item loader__item--1\"><\/div>\n\t\t<div class=\"loader__item loader__item--2\"><\/div>\n\t\t<div class=\"loader__item loader__item--3\"><\/div>\n\t<\/div>\n<\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large wrapper__divider-bottom-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"monitoring\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-cards-grid js-block-cards-grid\" data-items-per-line=3>\n\t\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tApp Store<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/AppStore.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/ai-energy\/id1607454432\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_appstore_download \" id=\"\" title=\"Transferir --&gt; Descargar\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tTransferir &#8211;&gt; Descargar\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tLigue e monitorize os inversores utilizando as nossas aplica\u00e7\u00f5es m\u00f3veis nativas. Transfira a partir da sua loja de aplica\u00e7\u00f5es preferida.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tGoogle Play<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/GooglePlay.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aiswei.international\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_googleplay_download \" id=\"\" title=\"Centro de transfer\u00eancias\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tCentro de transfer\u00eancias\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tLigue e monitorize os inversores utilizando as nossas aplica\u00e7\u00f5es m\u00f3veis nativas. Transfira a partir da sua loja de aplica\u00e7\u00f5es preferida.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tWeb Cloud<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-Icon-Computer-1-e1605044361670.png\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro  card-simple__outro--has-buttonpopup card-simple__outro--has-buttonpopup\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn btn-popup\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-31601\" id=\" sg-popup-id-31601\" title=\" For Business Partner\" aria-label=\"\">\n\t\t\t For Business Partner\t\t<\/a>\n\t<\/div><div class=\"btn__wrap btn__align--center card-simple__btn btn-popupn\">\n\t\t\t<a href=\"#%20\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-37521\" id=\" sg-popup-id-37521\" title=\"For End User\" aria-label=\"\">\n\t\t\tFor End User\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\tMonitorize os inversores utilizando a Web Cloud. Visite o nosso servi\u00e7o de armazenamento em nuvem diretamente aqui.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--60\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"faq\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tPerguntas e Respostas<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery  wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-faq__anchor\" id=\"faq\"><\/div>\n\n<div class=\"block-faq js-accordion\">\n\n\t\n\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Produz inversores de bateria (armazenamento)?\">\n\t\tProduz inversores de bateria (armazenamento)?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSim, o inversor h\u00edbrido Solplanet ser\u00e1 lan\u00e7ado em 2021.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Os inversores Solplanet t\u00eam prote\u00e7\u00e3o de tens\u00e3o (prote\u00e7\u00e3o de corrente)?\">\n\t\tOs inversores Solplanet t\u00eam prote\u00e7\u00e3o de tens\u00e3o (prote\u00e7\u00e3o de corrente)?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSim.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"O que \u00e9 que um inversor faria sob uma temperatura ambiente elevada?\">\n\t\tO que \u00e9 que um inversor faria sob uma temperatura ambiente elevada?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tO inversor diminuir\u00e1 automaticamente a sua pot\u00eancia de sa\u00edda para se proteger contra o sobreaquecimento. Pode encontrar a curva de redu\u00e7\u00e3o de pot\u00eancia dos inversores no manual de instru\u00e7\u00f5es e de instala\u00e7\u00e3o.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"A Solplanet tem uma solu\u00e7\u00e3o de controlo de exporta\u00e7\u00e3o 0?\">\n\t\tA Solplanet tem uma solu\u00e7\u00e3o de controlo de exporta\u00e7\u00e3o 0?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSim. Todos os inversores Solplanet, atrav\u00e9s do nosso registador de dados AiCom e do contador inteligente definido, podem obter a fun\u00e7\u00e3o de exporta\u00e7\u00e3o 0 atrav\u00e9s da configura\u00e7\u00e3o no servidor Web\/APP\/AiSWEI do registador de dados.<br>Para os inversores residenciais Solplanet, tamb\u00e9m \u00e9 poss\u00edvel ter uma solu\u00e7\u00e3o de controlo de exporta\u00e7\u00e3o atrav\u00e9s da liga\u00e7\u00e3o do contador inteligente definido diretamente ao inversor via RS485 e ativar esta fun\u00e7\u00e3o na APP.<br>Para mais informa\u00e7\u00f5es, consulte os manuais do utilizador ou contacte o nosso servi\u00e7o de apoio t\u00e9cnico.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Posso sobredimensionar o painel fotovoltaico em rela\u00e7\u00e3o \u00e0 capacidade do inversor?\">\n\t\tPosso sobredimensionar o painel fotovoltaico em rela\u00e7\u00e3o \u00e0 capacidade do inversor?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tSim, a capacidade CC do gerador fotovoltaico pode exceder a capacidade CA do inversor. Os valores da rela\u00e7\u00e3o CC\/CA para cada tipo de inversor est\u00e3o indicados nesta ficha de dados. Como regra geral, o painel fotovoltaico pode ser sobredimensionado em 50%. Isto depende da localiza\u00e7\u00e3o e dos n\u00edveis de irradia\u00e7\u00e3o do local. A sobredimens\u00e3o excessiva do gerador fotovoltaico implica um desperd\u00edcio de dinheiro e causa algum impacto na fiabilidade do inversor. Em caso de d\u00favida sobre o dimensionamento excessivo, consulte uma ferramenta de dimensionamento ou contacte o seu especialista t\u00e9cnico local da Solplanet.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Posso usar m\u00f3dulos de pel\u00edcula fina nos Inversores Solplanet?\">\n\t\tPosso usar m\u00f3dulos de pel\u00edcula fina nos Inversores Solplanet?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tOs inversores Solplanet n\u00e3o podem ser utilizados com m\u00f3dulos de pel\u00edcula fina, pois estes necessitam de uma liga\u00e7\u00e3o \u00e0 terra funcional no condutor CC positivo ou negativo. Nestes casos, sugerimos a utiliza\u00e7\u00e3o de um inversor isolado (baseado num transformador). Os nossos inversores n\u00e3o isolados (sem transformador) s\u00e3o normalmente concebidos para m\u00f3dulos solares de sil\u00edcio. No entanto, existem pain\u00e9is solares de pel\u00edcula fina que n\u00e3o necessitam de uma liga\u00e7\u00e3o \u00e0 terra funcional e, nestes casos, um inversor Solplanet funcionar\u00e1 corretamente. Antes de planear a sua instala\u00e7\u00e3o, consulte o seu fornecedor de m\u00f3dulos ou contacte o nosso servi\u00e7o de apoio t\u00e9cnico.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Os inversores Solplanet podem ser usados em sistemas fora da rede que incluem um gerador a diesel?\">\n\t\tOs inversores Solplanet podem ser usados em sistemas fora da rede que incluem um gerador a diesel?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tOs inversores Solplanet s\u00e3o inversores de rede e, como tal, o lado AC do inversor deve ser ligado \u00e0 rede el\u00e9trica. N\u00e3o existem defini\u00e7\u00f5es que permitam que o inversor funcione no modo &#8220;fora da rede&#8221; ou &#8220;ilha&#8221;. A Solplanet n\u00e3o pode garantir o funcionamento correto em aplica\u00e7\u00f5es fora da rede e n\u00e3o garantir\u00e1 quaisquer danos no inversor ou na instala\u00e7\u00e3o FV que possam ser causados em condi\u00e7\u00f5es &#8220;fora da rede&#8221;.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Os inversores Solplanet s\u00e3o isolados ou n\u00e3o?\">\n\t\tOs inversores Solplanet s\u00e3o isolados ou n\u00e3o?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tA Solplanet produz apenas inversores n\u00e3o isolados (sem transformador). O inversor sem transformador \u00e9 o inversor mais comum no mercado residencial e comercial, e geralmente tem uma maior efici\u00eancia, menor custo, menor tamanho e menor peso em compara\u00e7\u00e3o com os inversores isolados (transformador).<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"O inversor est\u00e1 equipado com um interruptor CC?\">\n\t\tO inversor est\u00e1 equipado com um interruptor CC?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tTodos os inversores Solplanet est\u00e3o equipados com um interruptor DC por defeito.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_pt-pt\" aria-label=\"Como selecionar o inversor de tamanho correto?\">\n\t\tComo selecionar o inversor de tamanho correto?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tPode utilizar software de terceiros ou contactar o nosso apoio t\u00e9cnico para obter ajuda.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--120\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/pt-pt\/questions-answers\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Visite nossa se\u00e7\u00e3o completa de perguntas frequentes\" aria-label=\"\">\n\t\t\tVisite nossa se\u00e7\u00e3o completa de perguntas frequentes\t\t<\/a>\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--120 wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"warranty\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading block-heading--with-image block-heading--center-mobile\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\tA nossa garantia excecional<\/h2>\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/10\/Screenshot-2020-10-23-at-12.49.24.png\" class=\"image block-heading__image\" \/><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--80\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--big block-columns__vertical-spacing-large--big\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tInforma\u00e7\u00f5es sobre a garantia<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tTodos os produtos da Solpanet s\u00e3o produzidos de acordo com as normas internacionais de qualidade. Oferecemos uma garantia padr\u00e3o de at\u00e9 6 anos sem afetar a garantia legal fornecida por qualquer grossista ou retalhista.<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/07\/S-PM21-006-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V1.9.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Garantia Internacional\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tGarantia Internacional\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/07\/battery-warranty.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Battery Warranty\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tBattery Warranty\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/EV-Charger-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V1.3.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"EV Charger Warranty\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tEV Charger Warranty\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tEstado da garantia<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tPretende verificar o estado da garantia do seu produto? Damos-lhe acesso \u00e0 base de dados de garantia da empresa AISWEI, propriet\u00e1ria da Solplanet, para que possa verificar facilmente o estado da garantia.<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\/warrantySearch\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Verifique o estado da garantia\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tVerifique o estado da garantia\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\tExtens\u00e3o da garantia<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tPretende prolongar a sua garantia? Inicie sess\u00e3o ou crie uma conta na AISWEI, a empresa propriet\u00e1ria da Solplanet, e adquira uma extens\u00e3o de garantia por apenas 30 euros por 5 anos adicionais ou mais.\u00a0<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"Adquira uma extens\u00e3o da garantia\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\tAdquira uma extens\u00e3o da garantia\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"claims\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--right\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Online-Claim-page-banner-CPs2X8JYmS8-unsplash.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\tFALE CONNOSCO SOBRE O ASSUNTO<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tNecessita de comunicar um problema?<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tOs produtos Solplanet s\u00e3o feitos para durar, mas poder\u00e1 ter de enfrentar algum problema. Por favor, apresente a reclama\u00e7\u00e3o e explique o caso. As nossas equipas regionais garantir\u00e3o que a equipa de assist\u00eancia local correta entra em contacto consigo brevemente para resolver o problema.<\/p>\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--10 wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/onlineclaim-solplanet.aiswei-tech.com\/#\/en\/OnlineClaim\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_selectcountry \" id=\"\" title=\"Report a problem \" aria-label=\"\">\n\t\t\tReport a problem \t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"contact-us\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--left\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/Image-component.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tContacte-nos diretamente<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\tCaso tenha algum problema ou quest\u00e3o urgente, n\u00e3o hesite em contactar-nos diretamente.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/pt-pt\/contact-us\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_contactus \" id=\"\" title=\"Contacte-nos\" aria-label=\"\">\n\t\t\tContacte-nos\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Installer Area | Solplanet<\/title>\n<meta name=\"description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installer Area | Solplanet\" \/>\n<meta property=\"og:description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador\" \/>\n<meta property=\"og:site_name\" content=\"Solplanet\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-06T03:25:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador\",\"url\":\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador\",\"name\":\"Installer Area | Solplanet\",\"isPartOf\":{\"@id\":\"https:\/\/solplanet.net\/pt-pt#website\"},\"datePublished\":\"2020-09-15T11:54:17+00:00\",\"dateModified\":\"2024-03-06T03:25:22+00:00\",\"description\":\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\",\"breadcrumb\":{\"@id\":\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solplanet.net\/pt-pt\/area-do-instalador#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solplanet.net\/pt-pt\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installer Area\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solplanet.net\/pt-pt#website\",\"url\":\"https:\/\/solplanet.net\/pt-pt\",\"name\":\"Solplanet\",\"description\":\"Solar for everybody\",\"publisher\":{\"@id\":\"https:\/\/solplanet.net\/pt-pt#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solplanet.net\/pt-pt?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/solplanet.net\/pt-pt#organization\",\"name\":\"Solplanet\",\"url\":\"https:\/\/solplanet.net\/pt-pt\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/solplanet.net\/pt-pt#\/schema\/logo\/image\/\",\"url\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"contentUrl\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"width\":500,\"height\":500,\"caption\":\"Solplanet\"},\"image\":{\"@id\":\"https:\/\/solplanet.net\/pt-pt#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installer Area | Solplanet","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador","og_locale":"pt_PT","og_type":"article","og_title":"Installer Area | Solplanet","og_description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","og_url":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador","og_site_name":"Solplanet","article_modified_time":"2024-03-06T03:25:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador","url":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador","name":"Installer Area | Solplanet","isPartOf":{"@id":"https:\/\/solplanet.net\/pt-pt#website"},"datePublished":"2020-09-15T11:54:17+00:00","dateModified":"2024-03-06T03:25:22+00:00","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","breadcrumb":{"@id":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solplanet.net\/pt-pt\/area-do-instalador"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solplanet.net\/pt-pt\/area-do-instalador#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solplanet.net\/pt-pt"},{"@type":"ListItem","position":2,"name":"Installer Area"}]},{"@type":"WebSite","@id":"https:\/\/solplanet.net\/pt-pt#website","url":"https:\/\/solplanet.net\/pt-pt","name":"Solplanet","description":"Solar for everybody","publisher":{"@id":"https:\/\/solplanet.net\/pt-pt#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplanet.net\/pt-pt?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/solplanet.net\/pt-pt#organization","name":"Solplanet","url":"https:\/\/solplanet.net\/pt-pt","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/solplanet.net\/pt-pt#\/schema\/logo\/image\/","url":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","contentUrl":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","width":500,"height":500,"caption":"Solplanet"},"image":{"@id":"https:\/\/solplanet.net\/pt-pt#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/pages\/64607"}],"collection":[{"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/comments?post=64607"}],"version-history":[{"count":8,"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/pages\/64607\/revisions"}],"predecessor-version":[{"id":108863,"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/pages\/64607\/revisions\/108863"}],"wp:attachment":[{"href":"https:\/\/solplanet.net\/pt-pt\/wp-json\/wp\/v2\/media?parent=64607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}