{"id":13013,"date":"2020-09-15T11:54:17","date_gmt":"2020-09-15T11:54:17","guid":{"rendered":"https:\/\/solplanet.net\/?page_id=13013"},"modified":"2025-03-25T10:39:20","modified_gmt":"2025-03-25T10:39:20","slug":"installer-area-kr","status":"publish","type":"page","link":"https:\/\/solplanet.net\/ko\/installer-area-kr","title":{"rendered":"\uc124\uce58\uc790 \uc601\uc5ed"},"content":{"rendered":"<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/FOTO-Featured-HomePage.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--big jumbotron__heading\">\n\t\uc194\ud50c\ub798\ub2db\uc740 \ubaa8\ub4e0 \uc81c\ud488\uc744 \ub2e8\uc21c\ud558\uac8c \ub9cc\ub4ed\ub2c8\ub2e4.<\/h1><p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\t\uc124\uce58\uac00 \uc27d\uace0 \uc2e0\ub8b0\uc131\uc774 \ub192\uc73c\uba70 \uc0ac\uc6a9\uc790 \uce5c\ud654\uc801\uc785\ub2c8\ub2e4.<\/p>\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--100 wrapper__spacing-bottom-large--180\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--default block-columns__vertical-spacing-large--default\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\t\uc194\ud50c\ub798\ub2db\uc740 \ubaa8\ub4e0 \uc81c\ud488\uc744 \ub2e8\uc21c\ud558\uac8c \ub9cc\ub4ed\ub2c8\ub2e4.<\/h2>\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--7 block-column__width-tablet--12 block-column__offset-large--1 block-column__offset-tablet--0 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc194\ud50c\ub798\ub2db\uc744 \uc0ac\uc6a9\ud558\uba74 \ubaa8\ub4e0 \uac83\uc774 \uc26c\uc6cc\uc9d1\ub2c8\ub2e4. <br><br>\uc194\ud50c\ub798\ub2db\uc758 \uc81c\ud488\uc740 \uc124\uce58\uac00 \uc27d\uace0 \uc2e0\ub8b0\uc131\uc774 \ub192\uc73c\uba70 \uc0ac\uc6a9\ud558\uae30 \uc27d\uc2b5\ub2c8\ub2e4. \uc194\ud50c\ub798\ub2db\uc740 \ucd5c\uace0\uc758 \uc131\ub2a5\uacfc \uc2e0\ub8b0\uc131\uc744 \uc720\uc9c0\ud558\uba74\uc11c \uc81c\ud488, \uc5b4\ud50c\ub9ac\ucf00\uc774\uc158 \ubc0f \uc815\ubcf4\ub97c \ubcf4\ub2e4 \ube60\ub974\uace0 \uc27d\uac8c \uc0ac\uc6a9\ud560 \uc218 \uc788\ub3c4\ub85d \uc9c0\uc18d\uc801\uc73c\ub85c \ub178\ub825\ud558\uace0 \uc788\uc2b5\ub2c8\ub2e4.<br><\/p>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--60\" id=\"video-center\">\n\t<div class=\"wrapper__anchor\" id=\"video-center\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default block-heading__heading\">\n\t\ub3d9\uc601\uc0c1 \uc790\ub8cc<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--0 wrapper__spacing-bottom-large--100\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"videos\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div\n\tclass=\"block-carousel js-block-carousel swiper-container block-carousel__pagination-type-under\"\n\tdata-swiper-loop=\"1\"\n\tdata-show-items=\"2\"\n>\n\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Vaconn-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0923c\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0923c\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0923c-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/t15zxnm288Q?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Phoenix-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d09a32\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d09a32\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d09a32-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/iDiP44LgbYw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10k-S-Vaconn-DC-terminal-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0a19a\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0a19a\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0a19a-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/TJj4APZDKEA?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW-6-10K-S-PhoenixDCTerminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6 10k S Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0a8e8\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0a8e8\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0a8e8-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/z0mbp5Sblhc?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/one-phase-installation-2.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSingle phase installation<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0aff9\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0aff9\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0aff9-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/EaUn9kaeC50?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/three-phase-installation-2-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tThree phase installation<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0b762\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0b762\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0b762-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/6GPw17R6dWU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW-3-5000-H-S-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW3000 5000 H-S installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0bd6c\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0bd6c\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0bd6c-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Aq8Erlfe9c0?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW8-20K-LT-G2-Thumbnail-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW8K 20K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0c41f\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0c41f\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0c41f-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/\/3BVaGCqpBUk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW30-50K-LT-G2-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW30K 50K LT-G2 installation video<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0ca5e\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0ca5e\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0ca5e-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Y3y_DifPydU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/glenn-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tGlen installed one blindfolded<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0d378\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0d378\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0d378-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/0b9owCCXDoo?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2021\/01\/Glen-ASW-T-Series.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-center\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tUnboxing of<br>ASW T Series<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841296456a57a86d0d9b1\" aria-label=\"\ub3d9\uc601\uc0c1 \uc7ac\uc0dd\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841296456a57a86d0d9b1\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\ub2eb\uae30\" aria-label=\"\ub2eb\uae30 \ubaa8\ub4dc\" data-micromodal-close=\"true\">\n\t\t\t\ub2eb\uae30\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841296456a57a86d0d9b1-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--twentyone-nine jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/srgLj0Gvf-M?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<\/div>\n\n\t<div class=\"carousel-navigation carousel-navigation__theme--dark block-carousel__carousel-navigation\">\n\t<div class=\"carousel-navigation__item carousel-navigation__item--prev js-block-carousel-prev-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M1 20L21 1M21 39L1 20\" \/><\/g><\/svg>\n\t<\/div>\n\t<div class=\"carousel-navigation__item carousel-navigation__item--next js-block-carousel-next-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M21 20L1 1M1 39l20-19\" \/><\/g><\/svg>\n\t<\/div>\n<\/div><div class=\"carousel-pagination js-block-carousel-pagination carousel-pagination__theme--dark block-carousel__carousel-pagination\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--sand wrapper__spacing-top-large--40 wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"downloads\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-documents\">\n\t\t\t<div class=\"block-documents__intro\">\n\t\t\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-documents__heading heading__color--is-gradient\">\n\t\ub2e4\uc6b4\ub85c\ub4dc\uc13c\ud130<\/h2>\t\t<\/div>\n\t\n\t<div class=\"documents js-documents\">\n\t<div class=\"documents__filter documents-filter js-documents-placeholder\">\n\t\t<ul class=\"111  documents-filter__list js-documents-list\" data-index=\"0\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"294\" data-type=\"term\">\n\t\t\t\t\ub370\uc774\ud130\uc2dc\ud2b8\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"295\" data-type=\"term\">\n\t\t\t\t\uc124\uce58 \uc18c\uac1c\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"293\" data-type=\"term\">\n\t\t\t\t\uc778\uc99d\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"296\" data-type=\"term\">\n\t\t\t\t\uc81c\ud488 \ube0c\ub85c\uc154\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul>\t<\/div>\n\t<div class=\"documents__single js-documents-details\">\n\t\t\t<\/div>\n\n\t<div class=\"loader loader--use-overlay documents__loader\">\n\t<div class=\"loader__load\">\n\t\t<div class=\"loader__item loader__item--1\"><\/div>\n\t\t<div class=\"loader__item loader__item--2\"><\/div>\n\t\t<div class=\"loader__item loader__item--3\"><\/div>\n\t<\/div>\n<\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large wrapper__divider-bottom-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"monitoring\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-cards-grid js-block-cards-grid\" data-items-per-line=3>\n\t\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\t\uc571 \uc2a4\ud1a0\uc5b4<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/AppStore.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/ai-energy\/id1607454432\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_appstore_download \" id=\"\" title=\"\ub2e4\uc6b4\ub85c\ub4dc\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\ub2e4\uc6b4\ub85c\ub4dc\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\ub2f9\uc0ac\uc758 \uae30\ubcf8 \ubaa8\ubc14\uc77c \uc571\uc744 \uc0ac\uc6a9\ud558\uc5ec \uc778\ubc84\ud130\ub97c \uc5f0\uacb0\ud558\uace0 \ubaa8\ub2c8\ud130\ub9c1 \ud558\uc2ed\uc2dc\uc624. \uc120\ud638\ud558\ub294 \uc571 \uc2a4\ud1a0\uc5b4\uc5d0\uc11c \ub2e4\uc6b4\ub85c\ub4dc \ud558\uc2ed\uc2dc\uc624.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\t\uad6c\uae00\ud50c\ub808\uc774<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/GooglePlay.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aiswei.international\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_googleplay_download \" id=\"\" title=\"\ub2e4\uc6b4\ub85c\ub4dc\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\ub2e4\uc6b4\ub85c\ub4dc\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\ub2f9\uc0ac\uc758 \uae30\ubcf8 \ubaa8\ubc14\uc77c \uc571\uc744 \uc0ac\uc6a9\ud558\uc5ec \uc778\ubc84\ud130\ub97c \uc5f0\uacb0\ud558\uace0 \ubaa8\ub2c8\ud130\ub9c1 \ud558\uc2ed\uc2dc\uc624. \uc120\ud638\ud558\ub294 \uc571 \uc2a4\ud1a0\uc5b4\uc5d0\uc11c \ub2e4\uc6b4\ub85c\ub4dc \ud558\uc2ed\uc2dc\uc624.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\t\uc6f9 \ubaa8\ub2c8\ud130\ub9c1<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-Icon-Computer-1-e1605044361670.png\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro  card-simple__outro--has-buttonpopup card-simple__outro--has-buttonpopup\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn btn-popup\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-161093\" id=\" sg-popup-id-161093\" title=\"\ube44\uc988\ub2c8\uc2a4 \ud30c\ud2b8\ub108\uc6a9\" aria-label=\"\">\n\t\t\t\ube44\uc988\ub2c8\uc2a4 \ud30c\ud2b8\ub108\uc6a9\t\t<\/a>\n\t<\/div><div class=\"btn__wrap btn__align--center card-simple__btn btn-popupn\">\n\t\t\t<a href=\"https:\/\/www.aisweicloud.com\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_monitorweb_download\" id=\"\" title=\"\ucd5c\uc885 \uc0ac\uc6a9\uc790\uc6a9\" aria-label=\"\">\n\t\t\t\ucd5c\uc885 \uc0ac\uc6a9\uc790\uc6a9\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\uc6f9 \ud074\ub77c\uc6b0\ub4dc\ub97c \uc0ac\uc6a9\ud558\uc5ec \uc778\ubc84\ud130\ub97c \ubaa8\ub2c8\ud130\ub9c1 \ud569\ub2c8\ub2e4. \uc5ec\uae30\uc5d0\uc11c \uc9c1\uc811 \ud074\ub77c\uc6b0\ub4dc \uc11c\ube44\uc2a4\ub97c \ubc29\ubb38\ud558\uc2ed\uc2dc\uc624.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--60\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"faq\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t\uc9c8\ubb38 \ubc0f \ub2f5\ubcc0<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--60 wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-faq__anchor\" id=\"faq\"><\/div>\n\n<div class=\"block-faq js-accordion\">\n\n\t\n\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"\ubcf4\uc99d \uae30\uac04\uc744 \uc5f0\uc7a5\ud558\ub824\uba74 \uc5b4\ub5bb\uac8c \ud574\uc57c \ud569\ub2c8\uae4c?\">\n\t\t\ubcf4\uc99d \uae30\uac04\uc744 \uc5f0\uc7a5\ud558\ub824\uba74 \uc5b4\ub5bb\uac8c \ud574\uc57c \ud569\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t<a href=\"http:\/\/warranty.aiswei-tech.com\/#\/login\" data-type=\"URL\" data-id=\"http:\/\/warranty.aiswei-tech.com\/#\/login\">\uc774 \ud3ec\ud138\uc744 \ud1b5\ud574<\/a><\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"\uc778\ubc84\ud130\uc758 \ud604\uc7ac \ubcf4\uc99d \uc0c1\ud0dc\ub294 \uc5b4\ub514\uc5d0\uc11c \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\uae4c?\">\n\t\t\uc778\ubc84\ud130\uc758 \ud604\uc7ac \ubcf4\uc99d \uc0c1\ud0dc\ub294 \uc5b4\ub514\uc5d0\uc11c \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t<a href=\"http:\/\/warranty.aiswei-tech.com\/#\/yanbao-search\" data-type=\"URL\" data-id=\"http:\/\/warranty.aiswei-tech.com\/#\/yanbao-search\">\uc5ec\uae30\uc5d0\uc11c \ucc3e\uc744 \uc218 \uc788\uc5b4\uc694<\/a>.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"Solplanet \uc778\ubc84\ud130\ub294 \ud0c0\uc0ac \ub370\uc774\ud130 \ub85c\uac70\ub97c \uc9c0\uc6d0\ud569\ub2c8\uae4c?\">\n\t\tSolplanet \uc778\ubc84\ud130\ub294 \ud0c0\uc0ac \ub370\uc774\ud130 \ub85c\uac70\ub97c \uc9c0\uc6d0\ud569\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc608, Solplanet \uc778\ubc84\ud130\ub294 Solarlog, \uae30\uc0c1\uad00\uc81c \ubc0f Solarman\uacfc \uac19\uc740 \ud0c0\uc0ac \ub370\uc774\ud130\ub85c\uadf8\ub97c \uc9c0\uc6d0\ud569\ub2c8\ub2e4. \ub610\ud55c \ub300\ud615 PV \ud50c\ub79c\ud2b8\uc758 \uacbd\uc6b0 \ud0c0\uc0ac \uc81c\ud488\uc5d0 \ud504\ub85c\ud1a0\ucf5c\uc744 \uc81c\uacf5\ud558\uc5ec \uc790\uccb4 \ub9de\ucda4\ud615 \ubaa8\ub2c8\ud130\ub9c1 \uc194\ub8e8\uc158\uc744 \uac1c\ubc1c\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"AISWEI \ud074\ub77c\uc6b0\ub4dc \uc571\uc740 \uc5b4\ub5bb\uac8c \uc124\uce58\ud569\ub2c8\uae4c?\">\n\t\tAISWEI \ud074\ub77c\uc6b0\ub4dc \uc571\uc740 \uc5b4\ub5bb\uac8c \uc124\uce58\ud569\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc571\uc2a4\ud1a0\uc5b4 \ub610\ub294 \uad6c\uae00 \ud50c\ub808\uc774\uc5d0\uc11c <a href=\"https:\/\/apps.apple.com\/nl\/app\/aiswei\/id1465242250\" data-type=\"URL\" data-id=\"https:\/\/apps.apple.com\/nl\/app\/aiswei\/id1465242250\">\ub2e4\uc6b4\ub85c\ub4dc \ud560<\/a> \uc218 <a href=\"https:\/\/apps.apple.com\/nl\/app\/aiswei\/id1465242250\" data-type=\"URL\" data-id=\"https:\/\/apps.apple.com\/nl\/app\/aiswei\/id1465242250\">\uc788\uc2b5\ub2c8\ub2e4<\/a>.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"\ubc30\ud130\ub9ac(\uc800\uc7a5) \uc778\ubc84\ud130\ub97c \uc0dd\uc0b0\ud569\ub2c8\uae4c?\">\n\t\t\ubc30\ud130\ub9ac(\uc800\uc7a5) \uc778\ubc84\ud130\ub97c \uc0dd\uc0b0\ud569\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\ub124, Solplanet \ud558\uc774\ube0c\ub9ac\ub4dc \uc778\ubc84\ud130\ub294 2021\ub144\uc5d0 \ucd9c\uc2dc\ub420 \uc608\uc815\uc785\ub2c8\ub2e4.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"\uc778\ubc84\ud130 \uc6a9\ub7c9\uacfc \uad00\ub828\ud558\uc5ec PV \uc5b4\ub808\uc774\uc758 \ud06c\uae30\ub97c \ucd08\uacfc\ud560 \uc218 \uc788\uc2b5\ub2c8\uae4c?\">\n\t\t\uc778\ubc84\ud130 \uc6a9\ub7c9\uacfc \uad00\ub828\ud558\uc5ec PV \uc5b4\ub808\uc774\uc758 \ud06c\uae30\ub97c \ucd08\uacfc\ud560 \uc218 \uc788\uc2b5\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc608, PV\uc5b4\ub808\uc774 DC \uc6a9\ub7c9\uc774 \uc778\ubc84\ud130 AC\uc6a9\ub7c9\uc744 \ucd08\uacfc\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uac01 \uc778\ubc84\ud130 \uc720\ud615\uc5d0 \ub300\ud55c DC\/AC \ube44\uc728 \uac12\uc740 \uc774 \ub370\uc774\ud0c0\uc2dc\ud2b8\uc5d0 \ub098\uc5f4\ub418\uc5b4 \uc788\uc2b5\ub2c8\ub2e4. \uc77c\ubc18\uc801\uc778 \uacbd\ud5d8 \ubc95\uce59\uc740 PV\uc5b4\ub808\uc774\ub97c 50%\uae4c\uc9c0 \ud06c\uae30\ub97c \ucd08\uacfc\ud560 \uc218 \uc788\ub2e4\ub294 \uac83 \uc785\ub2c8\ub2e4. \uc774\ub294 \uc704\uce58 \ubc0f \ud604\uc7a5 \uc870\uc0ac \uc218\uc900\uc5d0 \ub530\ub77c \ub2e4\ub985\ub2c8\ub2e4. \uacfc\ub3c4\ud55c PV\uc5b4\ub808\uc774 \uc624\ubc84\uc0ac\uc774\uc9d5\uc740 \ube44\uc6a9\uc744 \ub0ad\ube44\ud558\uace0 \uc778\ubc84\ud130\uc758 \uc2e0\ub8b0\uc131\uc5d0 \uc57d\uac04\uc758 \uc601\ud5a5\uc744 \ubbf8\uce69\ub2c8\ub2e4. \ud2b9\ub300 \uc124\uacc4\uac00 \uc758\uc2ec\ub418\ub294 \uacbd\uc6b0 \ud06c\uae30 \uc870\uc815 \ub3c4\uad6c\ub97c \ucc38\uc870\ud558\uac70\ub098 \uc9c0\uc5ed Solplanet \uae30\uc220 \uc804\ubb38\uac00\uc5d0\uac8c \ubb38\uc758 \ud558\uc2ed\uc2dc\uc624.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_ko\" aria-label=\"\uc124\uce58 \uc9c0\uce68\uc740 \uc5b4\ub514\uc5d0\uc11c \ucc3e\uc744 \uc218 \uc788\uc2b5\ub2c8\uae4c?\">\n\t\t\uc124\uce58 \uc9c0\uce68\uc740 \uc5b4\ub514\uc5d0\uc11c \ucc3e\uc744 \uc218 \uc788\uc2b5\ub2c8\uae4c?\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc5ec\uae30\uc5d0\uc11c \uc124\uce58 \ub9e4\ub274\uc5bc\uc744 \ub2e4\uc6b4\ub85c\ub4dc\ud560 \uc218 <a href=\"\/ko\/downloads\/\" data-type=\"URL\" data-id=\"\/ko\/downloads\/\">\uc788\uc2b5\ub2c8\ub2e4<\/a>. \uc9e7\uace0 \uac04\ub2e8\ud55c \uc124\uce58 \ub3d9\uc601\uc0c1 \uc2dc\uccad\ud558\ub294 \uac83\uc774 \uc88b\uc2b5\ub2c8\ub2e4. \uc5ec\uae30\uc5d0\uc11c \ucc3e\uc744 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery  wrapper__spacing-bottom-large--70\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--small wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-group\">\n\t\n<div class=\"wrapper  wrapper__spacing-top-large--30 wrapper__spacing-bottom-large--120\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"\/ko\/questions-answers\/\" class=\"btn  btn__size--default btn__size-width--default \" id=\"\" title=\"\uc804\uccb4 FAQ\" aria-label=\"\">\n\t\t\t\uc804\uccb4 FAQ\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"warranty\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading block-heading--with-image block-heading--center-mobile\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\t\uc194\ud50c\ub798\ub2db\uc758 \uc81c\ud488 \ubcf4\uc99d<\/h2>\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/10\/Screenshot-2020-10-23-at-12.49.24.png\" class=\"image block-heading__image\" \/><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--80\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--big block-columns__vertical-spacing-large--big\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\ubcf4\uc99d \uc815\ubcf4<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\ubaa8\ub4e0 \uc194\ud50c\ub798\ub2db \uc81c\ud488\uc740 \uad6d\uc81c \ud488\uc9c8 \ud45c\uc900\uc5d0 \ub530\ub77c \uc81c\uc791\ub429\ub2c8\ub2e4. \uc194\ud50c\ub798\ub2db\uc740 \ub3c4\ub9e4 \ud639\uc740 \uc18c\ub9e4\uc5c5\uc790\uac00 \uc81c\uacf5\ud558\ub294 \ubc95\uc801 \ubcf4\uc99d\uc5d0 \uc601\ud5a5\uc744 \ubbf8\uce58\uc9c0 \uc54a\uace0 \ucd5c\ub300 20\ub144\uc758 \ubcf4\uc99d\uc744 \uc81c\uacf5\ud569\ub2c8\ub2e4.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2024\/10\/S-PM21-006-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V2.0.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\ud55c\uad6d \ubcf4\uc99d\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\ud55c\uad6d \ubcf4\uc99d\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\ubcf4\uc99d \uc0c1\ud0dc<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc81c\ud488\uc758 \ubcf4\uc99d \uc0c1\ud0dc\ub97c \ud655\uc778\ud558\uc2dc\uaca0\uc2b5\ub2c8\uae4c? \uc194\ud50c\ub798\ub2db\uc758 \ubcf4\uc99d \ub370\uc774\ud130\ubca0\uc774\uc2a4\uc5d0 \uc811\uadfc\ud558\uc5ec \ubcf4\uc99d \uc0c1\ud0dc\ub97c \uc27d\uac8c \ud655\uc778\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\/warrantySearch\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\ubcf4\uc99d \uc0c1\ud0dc \ud655\uc778\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\ubcf4\uc99d \uc0c1\ud0dc \ud655\uc778\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\ubcf4\uc99d \uc5f0\uc7a5<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\ubcf4\uc99d\uc744 \uc5f0\uc7a5\ud558\uc2dc\uaca0\uc2b5\ub2c8\uae4c? \uc194\ud50c\ub798\ub2db\uc5d0 \uacc4\uc815\uc744 \ub9cc\ub4e4\uace0 \ub85c\uadf8\uc778\ud558\uc5ec \ubcf4\uc99d \uc5f0\uc7a5\uc744 \uc2e0\uccad\ud558\uc138\uc694.<br><br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--center block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\ubcf4\uc99d \uc5f0\uc7a5 \ubc1b\uae30\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\ubcf4\uc99d \uc5f0\uc7a5 \ubc1b\uae30\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"claims\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--right\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Online-Claim-page-banner-CPs2X8JYmS8-unsplash.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t\uc815\ubcf4\ub97c \uc54c\ub824\uc8fc\uc138\uc694<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t\ubb38\uc81c\uac00 \uc788\uc73c\uc2e0\uac00\uc694?<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uc194\ud50c\ub798\ub2db \uc81c\ud488\uc740 \uc624\ub798 \uc0ac\uc6a9 \uac00\ub2a5\ud558\ub3c4\ub85d \ub9cc\ub4e4\uc5b4\uc84c\uc9c0\ub9cc \uc0ac\uc6a9 \uc911 \ubb38\uc81c\uac00 \ubc1c\uc0dd\ud560 \uc218 \uc788\uc2b5\ub2c8\ub2e4. \uc624\ub958 \ub0b4\uc6a9\uc744 \uc81c\ucd9c\ud558\uace0 \uc0ac\ub840\ub97c \uc124\uba85\ud558\uc2ed\uc2dc\uc624. \uad6d\ub0b4 \uc11c\ube44\uc2a4 \ub2f4\ub2f9\uc790\uac00 \ubb38\uc81c\ub97c \ud574\uacb0\ud558\uae30 \uc704\ud574 \uc2e0\uc18d\ud788 \uadc0\ud558\uc5d0\uac8c \uc5f0\ub77d\ud560 \uac83\uc785\ub2c8\ub2e4.<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/onlineclaim-solplanet.aiswei-tech.com\/#\/en\/OnlineClaim\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_selectcountry \" id=\"\" title=\"Report a problem\" aria-label=\"\">\n\t\t\tReport a problem\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"contact-us\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--left\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/Image-component.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t\uc194\ud50c\ub798\ub2db\uc5d0\uac8c \uc5f0\ub77d\ud558\uc2ed\uc2dc\uc624.<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\uae34\uae09 \uc0c1\ud669\uc778 \uacbd\uc6b0 \uc194\ud50c\ub798\ub2db\uc5d0 \ubc14\ub85c \uc5f0\ub77d\ud558\uc2ed\uc2dc\uc624.<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/ko\/contactus-kr\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_contactus \" id=\"\" title=\"\ubb38\uc758 \ud558\uae30\" aria-label=\"\">\n\t\t\t\ubb38\uc758 \ud558\uae30\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\uc124\uce58\uc790 \uc601\uc5ed | Solplanet<\/title>\n<meta name=\"description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplanet.net\/ko\/installer-area-kr\" \/>\n<meta property=\"og:locale\" content=\"ko_KR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\uc124\uce58\uc790 \uc601\uc5ed | Solplanet\" \/>\n<meta property=\"og:description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplanet.net\/ko\/installer-area-kr\" \/>\n<meta property=\"og:site_name\" content=\"Solplanet\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-25T10:39:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solplanet.net\/ko\/installer-area-kr\",\"url\":\"https:\/\/solplanet.net\/ko\/installer-area-kr\",\"name\":\"\uc124\uce58\uc790 \uc601\uc5ed | Solplanet\",\"isPartOf\":{\"@id\":\"https:\/\/solplanet.net\/ko#website\"},\"datePublished\":\"2020-09-15T11:54:17+00:00\",\"dateModified\":\"2025-03-25T10:39:20+00:00\",\"description\":\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\",\"breadcrumb\":{\"@id\":\"https:\/\/solplanet.net\/ko\/installer-area-kr#breadcrumb\"},\"inLanguage\":\"ko-KR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solplanet.net\/ko\/installer-area-kr\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solplanet.net\/ko\/installer-area-kr#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solplanet.net\/ko\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\uc124\uce58\uc790 \uc601\uc5ed\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solplanet.net\/ko#website\",\"url\":\"https:\/\/solplanet.net\/ko\",\"name\":\"Solplanet\",\"description\":\"Solar for everybody\",\"publisher\":{\"@id\":\"https:\/\/solplanet.net\/ko#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solplanet.net\/ko?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ko-KR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/solplanet.net\/ko#organization\",\"name\":\"Solplanet\",\"url\":\"https:\/\/solplanet.net\/ko\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ko-KR\",\"@id\":\"https:\/\/solplanet.net\/ko#\/schema\/logo\/image\/\",\"url\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"contentUrl\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"width\":500,\"height\":500,\"caption\":\"Solplanet\"},\"image\":{\"@id\":\"https:\/\/solplanet.net\/ko#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\uc124\uce58\uc790 \uc601\uc5ed | Solplanet","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplanet.net\/ko\/installer-area-kr","og_locale":"ko_KR","og_type":"article","og_title":"\uc124\uce58\uc790 \uc601\uc5ed | Solplanet","og_description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","og_url":"https:\/\/solplanet.net\/ko\/installer-area-kr","og_site_name":"Solplanet","article_modified_time":"2025-03-25T10:39:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solplanet.net\/ko\/installer-area-kr","url":"https:\/\/solplanet.net\/ko\/installer-area-kr","name":"\uc124\uce58\uc790 \uc601\uc5ed | Solplanet","isPartOf":{"@id":"https:\/\/solplanet.net\/ko#website"},"datePublished":"2020-09-15T11:54:17+00:00","dateModified":"2025-03-25T10:39:20+00:00","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","breadcrumb":{"@id":"https:\/\/solplanet.net\/ko\/installer-area-kr#breadcrumb"},"inLanguage":"ko-KR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solplanet.net\/ko\/installer-area-kr"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solplanet.net\/ko\/installer-area-kr#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solplanet.net\/ko"},{"@type":"ListItem","position":2,"name":"\uc124\uce58\uc790 \uc601\uc5ed"}]},{"@type":"WebSite","@id":"https:\/\/solplanet.net\/ko#website","url":"https:\/\/solplanet.net\/ko","name":"Solplanet","description":"Solar for everybody","publisher":{"@id":"https:\/\/solplanet.net\/ko#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplanet.net\/ko?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ko-KR"},{"@type":"Organization","@id":"https:\/\/solplanet.net\/ko#organization","name":"Solplanet","url":"https:\/\/solplanet.net\/ko","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"ko-KR","@id":"https:\/\/solplanet.net\/ko#\/schema\/logo\/image\/","url":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","contentUrl":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","width":500,"height":500,"caption":"Solplanet"},"image":{"@id":"https:\/\/solplanet.net\/ko#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/pages\/13013"}],"collection":[{"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/comments?post=13013"}],"version-history":[{"count":9,"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/pages\/13013\/revisions"}],"predecessor-version":[{"id":174113,"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/pages\/13013\/revisions\/174113"}],"wp:attachment":[{"href":"https:\/\/solplanet.net\/ko\/wp-json\/wp\/v2\/media?parent=13013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}