{"id":110484,"date":"2020-09-15T11:54:17","date_gmt":"2020-09-15T11:54:17","guid":{"rendered":"https:\/\/solplanet.net\/installer-area\/"},"modified":"2024-06-04T13:44:07","modified_gmt":"2024-06-04T13:44:07","slug":"installer-area","status":"publish","type":"page","link":"https:\/\/solplanet.net\/el\/installer-area","title":{"rendered":"Installer Area"},"content":{"rendered":"<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/FOTO-Featured-HomePage.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03a7\u03c1\u03b5\u03b9\u03ac\u03b6\u03b5\u03c3\u03c4\u03b5 \u03b2\u03bf\u03ae\u03b8\u03b5\u03b9\u03b1;<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--big jumbotron__heading\">\n\t\u0397 \u03c5\u03c0\u03cc\u03b8\u03b5\u03c3\u03b7 \u03c4\u03b7\u03c2 \u03b7\u03bb\u03b9\u03b1\u03ba\u03ae\u03c2 \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2 \u03bc\u03cc\u03bb\u03b9\u03c2 \u03ad\u03b3\u03b9\u03bd\u03b5 \u03b5\u03c5\u03ba\u03bf\u03bb\u03cc\u03c4\u03b5\u03c1\u03b7 \u03bc\u03b5 \u03c4\u03b7\u03bd Solplanet<\/h1><p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\t\u038c\u03bb\u03b7 \u03b7 \u03c5\u03c0\u03bf\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7 \u03c0\u03bf\u03c5 \u03b8\u03b1 \u03c7\u03c1\u03b5\u03b9\u03b1\u03c3\u03c4\u03b5\u03af\u03c4\u03b5 \u03b3\u03b9\u03b1 \u03c4\u03b1 Solplanet \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 \u03c3\u03b1\u03c2<\/p>\t\t<\/div>\n\t<\/div>\n\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--100 wrapper__spacing-bottom-large--180\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--default block-columns__vertical-spacing-large--default\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\t\u0395\u03cd\u03ba\u03bf\u03bb\u03b1 \u03c3\u03c4\u03b7\u03bd \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7, \u03b1\u03be\u03b9\u03cc\u03c0\u03b9\u03c3\u03c4\u03b1, \u03b5\u03cd\u03c7\u03c1\u03b7\u03c3\u03c4\u03b1 \u03ba\u03b1\u03b9 \u03b9\u03c3\u03c7\u03c5\u03c1\u03ac<\/h2>\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--7 block-column__width-tablet--12 block-column__offset-large--1 block-column__offset-tablet--0 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u03a3\u03c4\u03b7 Solplanet, \u03bf \u03c3\u03c4\u03cc\u03c7\u03bf\u03c2 \u03bc\u03b1\u03c2 \u03b5\u03af\u03bd\u03b1\u03b9 \u03bd\u03b1 \u03ba\u03ac\u03bd\u03bf\u03c5\u03bc\u03b5 \u03c4\u03b7\u03bd \u03b7\u03bb\u03b9\u03b1\u03ba\u03ae \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1 \u03c0\u03c1\u03bf\u03c3\u03b9\u03c4\u03ae \u03c3\u03b5 \u03cc\u03bb\u03bf\u03c5\u03c2, \u03ba\u03b1\u03b9 \u03b1\u03c5\u03c4\u03cc \u03c3\u03b7\u03bc\u03b1\u03af\u03bd\u03b5\u03b9 \u03cc\u03c4\u03b9 \u03c4\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 \u03bc\u03b1\u03c2 \u03c0\u03c1\u03ad\u03c0\u03b5\u03b9 \u03bd\u03b1 \u03b5\u03af\u03bd\u03b1\u03b9 \u03b1\u03c0\u03bb\u03ac \u03ba\u03b1\u03b9 \u03b5\u03cd\u03c7\u03c1\u03b7\u03c3\u03c4\u03b1. \u0393\u03b9\u03b1 \u03b1\u03c5\u03c4\u03cc \u03ba\u03b1\u03b9 \u03ba\u03ac\u03b8\u03b5 \u03b5\u03af\u03b4\u03bf\u03c2 \u03c4\u03bf \u03c3\u03c7\u03b5\u03b4\u03b9\u03ac\u03b6\u03bf\u03c5\u03bc\u03b5 \u03ad\u03c4\u03c3\u03b9 \u03ce\u03c3\u03c4\u03b5 \u03bd\u03b1 \u03b5\u03af\u03bd\u03b1\u03b9 \u03b5\u03cd\u03ba\u03bf\u03bb\u03bf \u03c3\u03c4\u03b7\u03bd \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7, \u03b1\u03be\u03b9\u03cc\u03c0\u03b9\u03c3\u03c4\u03bf \u03ba\u03b1\u03b9 \u03c6\u03b9\u03bb\u03b9\u03ba\u03cc \u03c0\u03c1\u03bf\u03c2 \u03c3\u03c4\u03bf \u03c7\u03c1\u03ae\u03c3\u03c4\u03b7.\u00a0<br><br>\u0394\u03b5\u03bd \u03c3\u03c4\u03b1\u03bc\u03b1\u03c4\u03ac\u03bc\u03b5 \u03b5\u03b4\u03ce. \u0395\u03c1\u03b3\u03b1\u03b6\u03cc\u03bc\u03b1\u03c3\u03c4\u03b5 \u03b4\u03b9\u03b1\u03c1\u03ba\u03ce\u03c2 \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03ba\u03ac\u03bd\u03bf\u03c5\u03bc\u03b5 \u03c4\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 \u03bc\u03b1\u03c2, \u03c4\u03b9\u03c2 \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ad\u03c2 \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03cd\u03b8\u03b7\u03c3\u03b7\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03b1 \u03b4\u03af\u03ba\u03c4\u03c5\u03b1 \u03b5\u03be\u03c5\u03c0\u03b7\u03c1\u03ad\u03c4\u03b7\u03c3\u03b7\u03c2 \u03c0\u03b5\u03bb\u03b1\u03c4\u03ce\u03bd \u03c4\u03b1\u03c7\u03cd\u03c4\u03b5\u03c1\u03b1 \u03ba\u03b1\u03b9 \u03c0\u03b9\u03bf \u03b5\u03cd\u03c7\u03c1\u03b7\u03c3\u03c4\u03b1, \u03b5\u03bd\u03ce \u03c0\u03b1\u03c1\u03ac\u03bb\u03bb\u03b7\u03bb\u03b1 \u03b4\u03b9\u03b1\u03c4\u03b7\u03c1\u03bf\u03cd\u03bc\u03b5 \u03c4\u03b7\u03bd \u03ba\u03bf\u03c1\u03c5\u03c6\u03b1\u03af\u03b1 \u03b1\u03c0\u03cc\u03b4\u03bf\u03c3\u03b7 \u03ba\u03b1\u03b9 \u03b1\u03be\u03b9\u03bf\u03c0\u03b9\u03c3\u03c4\u03af\u03b1 \u03c0\u03bf\u03c5 \u03c0\u03b5\u03c1\u03b9\u03bc\u03ad\u03bd\u03b5\u03c4\u03b5 \u03c3\u03c4\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 \u03c4\u03b7\u03c2 Solplanet.\u00a0<br><br><\/p>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--60\" id=\"video-center\">\n\t<div class=\"wrapper__anchor\" id=\"video-center\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default block-heading__heading\">\n\t\u0391\u03c1\u03c7\u03b5\u03af\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--90 wrapper__spacing-bottom-large--100\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"videos\"><\/div>\n\t\t\t<div class=\"wrapper__container\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div\n\tclass=\"block-carousel js-block-carousel swiper-container block-carousel__pagination-type-under\"\n\tdata-swiper-loop=\"1\"\n\tdata-show-items=\"2\"\n>\n\n\t<div class=\"swiper-wrapper\">\n\t\t\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2024\/03\/20240318-Upload-videos-Cover-Website-AiLogger-1000.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u0391\u03c0\u03bf\u03c4\u03b5\u03bb\u03b5\u03c3\u03bc\u03b1\u03c4\u03b9\u03ba\u03ae \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03cd\u03b8\u03b7\u03c3\u03b7<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tAi-Logger 1000\u00a0<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1557e39\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1557e39\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1557e39-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/WaIHdDwY8H8?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2024\/03\/20240223-Website-Cover-ASW-1-6k-S-G2-Seriespng.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03c3\u03b7\u03c2 \u0395\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2<br>\u039c\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03af \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 1-6k S G2 Series<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1558555\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1558555\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1558555-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/dpw_tN4TtT4?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2024\/02\/20240223-Website-Cover-AiPro10K.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u039c\u03c0\u03b1\u03c4\u03b1\u03c1\u03af\u03b5\u03c2 \u03c7\u03b1\u03bc\u03b7\u03bb\u03ae\u03c2 \u03c4\u03ac\u03c3\u03b7\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tAi-LB Pro 10K<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1558b90\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1558b90\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1558b90-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/IoR4rWZrCyI?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2024\/02\/20240223-Website-Cover-AiPro5K.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u039c\u03c0\u03b1\u03c4\u03b1\u03c1\u03af\u03b5\u03c2 \u03c7\u03b1\u03bc\u03b7\u03bb\u03ae\u03c2 \u03c4\u03ac\u03c3\u03b7\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tAi-LB Pro 5K<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc15591c6\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc15591c6\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc15591c6-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/uSxYS8s9BjY?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/10\/A-S-Still.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u039c\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03cc \u2013 \u038c\u03bb\u03b1 \u03c3\u03b5 \u0388\u03bd\u03b1<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW A-S Series<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1559798\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1559798\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1559798-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/wwtENfmvS6g?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/Ai-HB-G2-VideoStill-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u039c\u03c0\u03b1\u03c4\u03b1\u03c1\u03af\u03b1 \u03c5\u03c8\u03b7\u03bb\u03ae\u03c2 \u03c4\u03ac\u03c3\u03b7\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tAi-HB G2 Series<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1559e4c\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1559e4c\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1559e4c-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/JuQRJj9t1Z8?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/H-T2_T3_videoStill-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03a5\u03b2\u03c1\u03b9\u03b4\u03b9\u03ba\u03cc \u03c4\u03c1\u03b9\u03c6\u03b1\u03c3\u03b9\u03ba\u03cc<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 5-12K H-T2\/T3<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155a47f\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155a47f\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155a47f-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/UGUVIYNfOmI?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/H-S2-Video-Stills-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u039c\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03cc \u03a5\u03b2\u03c1\u03b9\u03b4\u03b9\u03ba\u03cc<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 3-6K H-S2<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155ab27\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155ab27\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155ab27-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/-Za34DKrvq4?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/ASW45-60K-LT-G3-Video-Stills.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03a4\u03c1\u03b9\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03af \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 45-60K LT-G3<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155b1ee\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155b1ee\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155b1ee-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/r1cKrH0rOtU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/ASW75-110K-LT-Video-Stills.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03a4\u03c1\u03b9\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03af \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 75-110K LT<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155b927\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155b927\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155b927-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/f9bERe3N7hw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/ASW-6-10K-S-Video-Stills.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--default jumbotron__intro\">\n\t\u03c3\u03b7\u03c2 \u0395\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2<br>\u039c\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03af \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2<\/p><h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW 6-10K S<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155bfd5\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155bfd5\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155bfd5-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/jXdxdAs_kYw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/12\/SOLPLANET-SOL-APOLLO-Cable-version-.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSOL APOLLO EV Charger<br>(Cable version)<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155c659\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155c659\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155c659-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/bHOYEjAViJk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/12\/SOLPLANET-SOL-APOLLO-Socket-version-.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tSOL APOLLO EV Charger<br>(Socket version)<br>\u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155cd34\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155cd34\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155cd34-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/ySozPINYQXg?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Vaconn-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Vaconn DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155d555\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155d555\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155d555-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/t15zxnm288Q?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/05\/20220519-InstallationVideos_Cover_ASW27-40K-LT-G3-Phoenix-DC-terminal.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\tASW27 40K LT G3 Phoenix DC terminal<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155db9c\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155db9c\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155db9c-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/iDiP44LgbYw?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/one-phase-installation-2.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\t\u039c\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03ae \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155e2a5\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155e2a5\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155e2a5-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/EaUn9kaeC50?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/three-phase-installation-2-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\t\u03a4\u03c1\u03b9\u03c6\u03b1\u03c3\u03b9\u03ba\u03ae \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155e8de\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155e8de\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155e8de-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/6GPw17R6dWU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW-3-5000-H-S-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW3000 5000 H-S \u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155ef3b\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155ef3b\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155ef3b-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Aq8Erlfe9c0?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW8-20K-LT-G2-Thumbnail-1.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW8K 20K LT-G2 \u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155f54e\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155f54e\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155f54e-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/\/3BVaGCqpBUk?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2022\/01\/ASW30-50K-LT-G2-Thumbnail.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tSolplanet ASW30K 50K LT-G2 \u0392\u03af\u03bd\u03c4\u03b5\u03bf \u03bc\u03b5 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc155fb98\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc155fb98\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc155fb98-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/Y3y_DifPydU?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/glenn-1.png)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--medium\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<h1 class=\"heading heading__align--left heading__color--white heading__size--medium jumbotron__heading\">\n\t\u039f \u0393\u03ba\u03bb\u03b5\u03bd \u03c4\u03bf\u03c0\u03bf\u03b8\u03ad\u03c4\u03b7\u03c3\u03b5 \u03ad\u03bd\u03b1 \u03bc\u03b5 \u03b4\u03b5\u03bc\u03ad\u03bd\u03b1 \u03bc\u03ac\u03c4\u03b9\u03b1<\/h1><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc1560177\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc1560177\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc1560177-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--default jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/0b9owCCXDoo?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\n<div class=\"block-carousel__item\"><div class=\"block-carousel__item-inner\"><div class=\"jumbotron block-jumbotron__jumbotron\">\n\n\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2021\/01\/Glen-ASW-T-Series.jpg)\" class=\"image-bg jumbotron__image-bg\"><\/div>\n\t<div class=\"jumbotron__mask jumbotron__mask-type--type1\"><\/div>\n\n\t<div class=\"\n\t\t\tjumbotron__content\n\t\t\tjumbotron__content--default\n\t\t\tjumbotron__content--vertical-center\n\t\t\tjumbotron__content--horizontal-left\n\t\t\">\n\t\t<div class=\"jumbotron__content-wrap\">\n\t\t\t<p class=\"paragraph paragraph__color--white paragraph__align--left paragraph__size--big jumbotron__paragraph\">\n\tUnboxing \u03c4\u03bf\u03c5<br>\u03a3\u03b5\u03b9\u03c1\u03ac ASW T<\/p><button class=\"video-button jumbotron__video-button\" role=\"button\" data-micromodal-trigger=\"block-jumbotron-17841428696a57dc156072f\" aria-label=\"\u03a0\u03b1\u03af\u03be\u03b5 \u03c4\u03bf \u03b2\u03af\u03bd\u03c4\u03b5\u03bf\">\n\t<svg class='video-button__icon' width='106' height='106' xmlns='http:\/\/www.w3.org\/2000\/svg'><g stroke='#FFF' fill='none' fill-rule='evenodd'><circle cx='53' cy='53' r='52' \/><path d='M78.764 53L40 72.382V33.618L78.764 53z' \/><\/g><\/svg><\/button>\t\t<\/div>\n\t<\/div>\n\n\t<div id=\"block-jumbotron-17841428696a57dc156072f\" class=\"modal js-modal\" aria-hidden=\"true\">\n\n\t<div class=\"modal__overlay\" data-micromodal-close>\n\n\t\t<div class=\"modal__dialog\" role=\"dialog\" aria-label=\"\">\n\n\t\t\t<header class=\"modal__header\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left modal__btn\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--big btn__size-width--default \" id=\"\" title=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b5\" aria-label=\"\u039a\u03bb\u03b5\u03af\u03c3\u03b9\u03bc\u03bf Modal\" data-micromodal-close=\"true\">\n\t\t\t\u039a\u03bb\u03b5\u03af\u03c3\u03b5\t\t<\/a>\n\t<\/div>\t\t\t<\/header>\n\n\t\t\t<section class=\"modal__content\" id=\"block-jumbotron-17841428696a57dc156072f-content\">\n\t\t\t\t<div class=\"video-iframe video-iframe__video-ratio--twentyone-nine jumbotron__video-iframe\">\n\t<iframe class=\"video-iframe__iframe\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/srgLj0Gvf-M?enablejsapi=1\" frameBorder=\"0\" allow=\"autoplay; fullscreen\" allowFullScreen><\/iframe>\n<\/div>\t\t\t<\/section>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<\/div>\n\n\t<div class=\"carousel-navigation carousel-navigation__theme--default block-carousel__carousel-navigation\">\n\t<div class=\"carousel-navigation__item carousel-navigation__item--prev js-block-carousel-prev-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M1 20L21 1M21 39L1 20\" \/><\/g><\/svg>\n\t<\/div>\n\t<div class=\"carousel-navigation__item carousel-navigation__item--next js-block-carousel-next-arrow\">\n\t\t<svg class=\"carousel-navigation__icon\" width=\"22\" height=\"40\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><g stroke=\"#FFF\" fill=\"none\" fill-rule=\"evenodd\" stroke-linecap=\"round\"><path d=\"M21 20L1 1M1 39l20-19\" \/><\/g><\/svg>\n\t<\/div>\n<\/div><div class=\"carousel-pagination js-block-carousel-pagination carousel-pagination__theme--dark block-carousel__carousel-pagination\"><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--sand wrapper__spacing-top-large--40 wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"downloads\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-documents\">\n\t\t\t<div class=\"block-documents__intro\">\n\t\t\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-documents__heading heading__color--is-gradient\">\n\t\u0391\u03c1\u03c7\u03b5\u03af\u03bf \u03bb\u03ae\u03c8\u03b5\u03c9\u03bd<\/h2>\t\t<\/div>\n\t\n\t<div class=\"documents js-documents\">\n\t<div class=\"documents__filter documents-filter js-documents-placeholder\">\n\t\t<ul class=\"111  documents-filter__list js-documents-list\" data-index=\"0\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1116\" data-type=\"term\">\n\t\t\t\tDatasheets\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1120\" data-type=\"term\">\n\t\t\t\tInstructions\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1123\" data-type=\"term\">\n\t\t\t\tCertificates\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1124\" data-type=\"term\">\n\t\t\t\tCompatibility list\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1130\" data-type=\"term\">\n\t\t\t\tTechnical Files\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"1121\" data-type=\"term\">\n\t\t\t\tBrochures\t\t\t<\/button>\n\t\t<\/li>\n\t\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item\" data-id=\"1127\" data-type=\"term\">\n\t\t\t\tSoftware\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul><ul class=\"111  documents-filter__list js-documents-list\" data-index=\"1\">\n\t\t\t<li class=\"documents-filter__item\">\n\t\t\t<button class=\"documents-filter__link js-documents-item is-active\" data-id=\"115254\" data-type=\"single\">\n\t\t\t\tProduct Brochure\t\t\t<\/button>\n\t\t<\/li>\n\t\t<\/ul>\t<\/div>\n\t<div class=\"documents__single js-documents-details\">\n\t\t<div class=\"documents-single\">\n\t\t\t<div class=\"documents-single__title\">\n\t\t\t\u039b\u03ae\u03c8\u03b5\u03b9\u03c2\t\t<\/div>\n\t\n\t<div class=\"documents-single__accordion js-accordion-downloads\">\n\t\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-downloads-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-downloads-trigger gtm_question_el\" aria-label=\"\u039c\u03c0\u03c1\u03bf\u03c3\u03bf\u03cd\u03c1\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03bf\u03c2\">\n\t\t\u039c\u03c0\u03c1\u03bf\u03c3\u03bf\u03cd\u03c1\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03bf\u03c2\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-downloads-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<ul class=\"documents-details\">\n\t\t\t<li class=\"documents-details__item\">\n\t\t\t<a class=\"documents-details__link\" href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Global-Brochure-EU-20250529-web.pdf\" download>\n\n\t\t\t\t<div class=\"documents-details__title\">\n\t\t\t\t\tSolplanet Product Brochure \t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"documents-details__version\">\n\t\t\t\t\tMay 2025\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"documents-details__language\">\n\t\t\t\t\t\t\u0391\u03b3\u03b3\u03bb\u03b9\u03ba\u03ac\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"documents-details__action\">\n\t\t\t\t\tpdf\t\t\t\t\t<svg class=\"documents-details__action-icon\" width=\"29\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M28.932 29.619l-.012.024a.661.661 0 01-.513.342l-.02.002-.049.002H.662a.667.667 0 01-.28-.062l-.012-.006a.66.66 0 01-.368-.544L0 29.327v-8.421a.662.662 0 011.321-.05l.002.05v7.759h26.353v-7.759a.662.662 0 011.322-.05l.002.05v8.421l-.004.049-.004.054a.657.657 0 01-.053.176l-.007.013zM14.5 0c.349 0 .635.27.66.612l.002.05-.001 20.062 6.783-6.782a.662.662 0 01.974.894l-.038.042-7.912 7.912-.01.008a.665.665 0 01-.058.05l.068-.058a.665.665 0 01-.172.124l-.01.004a.657.657 0 01-.286.065h-.017c-.011 0-.023 0-.034-.002l.051.002a.665.665 0 01-.292-.067l-.004-.002-.021-.011a.657.657 0 01-.09-.06l-.019-.015-.017-.015a.665.665 0 01-.008-.007L6.12 14.878a.662.662 0 01.894-.974l.042.038 6.782 6.782V.662c0-.366.297-.662.662-.662z\" fill=\"#555\" fill-rule=\"nonzero\" \/><\/svg>\n\t\t\t\t<\/div>\n\t\t\t<\/a>\n\n\t\t<\/li>\n          \t<\/ul>\t\t<\/div>\n\t<\/section>\n<\/div>\t<\/div>\n<\/div>\t<\/div>\n\n\t<div class=\"loader loader--use-overlay documents__loader\">\n\t<div class=\"loader__load\">\n\t\t<div class=\"loader__item loader__item--1\"><\/div>\n\t\t<div class=\"loader__item loader__item--2\"><\/div>\n\t\t<div class=\"loader__item loader__item--3\"><\/div>\n\t<\/div>\n<\/div><\/div><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large wrapper__divider-bottom-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"monitoring\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-cards-grid js-block-cards-grid\" data-items-per-line=3>\n\t\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tApp Store<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/AppStore.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/apps.apple.com\/us\/app\/ai-energy\/id1607454432\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_appstore_download \" id=\"\" title=\"\u039b\u03ae\u03c8\u03b7\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u039b\u03ae\u03c8\u03b7\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\u03a3\u03c5\u03bd\u03b4\u03ad\u03c3\u03c4\u03b5 \u03ba\u03b1\u03b9 \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ae\u03c3\u03c4\u03b5 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ce\u03bd\u03c4\u03b1\u03c2 \u03c4\u03b9\u03c2 \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ad\u03c2 \u03b3\u03b9\u03b1 \u03ad\u03be\u03c5\u03c0\u03bd\u03b5\u03c2 \u03c3\u03c5\u03c3\u03ba\u03b5\u03c5\u03ad\u03c2.\u00a0 \u039a\u03b1\u03c4\u03b5\u03b2\u03ac\u03c3\u03c4\u03b5 \u03c4\u03b9\u03c2 \u03b1\u03c0\u03cc \u03c4\u03bf app store \u03c4\u03b7\u03c2 \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae\u03c2 \u03c3\u03b1\u03c2.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tGoogle Play<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/GooglePlay.svg\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro card-simple__outro--has-button\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn\">\n\t\t\t<a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.aiswei.international\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_googleplay_download \" id=\"\" title=\"\u039b\u03ae\u03c8\u03b7\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u039b\u03ae\u03c8\u03b7\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\u03a3\u03c5\u03bd\u03b4\u03ad\u03c3\u03c4\u03b5 \u03ba\u03b1\u03b9 \u03c0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ae\u03c3\u03c4\u03b5 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ce\u03bd\u03c4\u03b1\u03c2 \u03c4\u03b9\u03c2 \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ad\u03c2 \u03b3\u03b9\u03b1 \u03ad\u03be\u03c5\u03c0\u03bd\u03b5\u03c2 \u03c3\u03c5\u03c3\u03ba\u03b5\u03c5\u03ad\u03c2.\u00a0 \u039a\u03b1\u03c4\u03b5\u03b2\u03ac\u03c3\u03c4\u03b5 \u03c4\u03b9\u03c2 \u03b1\u03c0\u03cc \u03c4\u03bf app store \u03c4\u03b7\u03c2 \u03b5\u03c0\u03b9\u03bb\u03bf\u03b3\u03ae\u03c2 \u03c3\u03b1\u03c2.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n<div class=\"card-simple block-card__card-simple\">\n\t\n\t\t\t\t\t<div class=\"card-simple__intro js-card-simple-intro\">\n\t\t\t\t<h2 class=\"heading heading__align--center heading__color--shaft heading__size--default card-simple__subheading\">\n\tWeb Cloud<\/h2>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__media js-card-simple-media\">\n\t\t\t\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-Icon-Computer-1-e1605044361670.png\" class=\"image card-simple__image\" \/>\t\t\t<\/div>\n\t\t\n\t\t\t\t\t<div class=\"card-simple__outro  card-simple__outro--has-buttonpopup card-simple__outro--has-buttonpopup\">\n\t\t\t\t<div class=\"btn__wrap btn__align--center card-simple__btn btn-popup\">\n\t\t\t<a href=\"#\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-31601\" id=\" sg-popup-id-31601\" title=\"\u0393\u03b9\u03b1 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c4\u03b5\u03c2 \u03ba\u03b1\u03b9 \u03bb\u03bf\u03b9\u03c0\u03bf\u03cd\u03c2 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b5\u03c2\" aria-label=\"\">\n\t\t\t\u0393\u03b9\u03b1 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c4\u03b5\u03c2 \u03ba\u03b1\u03b9 \u03bb\u03bf\u03b9\u03c0\u03bf\u03cd\u03c2 \u03c3\u03c5\u03bd\u03b5\u03c1\u03b3\u03ac\u03c4\u03b5\u03c2\t\t<\/a>\n\t<\/div><div class=\"btn__wrap btn__align--center card-simple__btn btn-popupn\">\n\t\t\t<a href=\"#%20\" class=\"btn btn__color--alto btn__size--default btn__size-width--default sg-popup-id-37521\" id=\" sg-popup-id-37521\" title=\"\u0393\u03b9\u03b1 \u03c4\u03b5\u03bb\u03b9\u03ba\u03bf\u03cd\u03c2 \u03c7\u03c1\u03ae\u03c3\u03c4\u03b5\u03c2\" aria-label=\"\">\n\t\t\t\u0393\u03b9\u03b1 \u03c4\u03b5\u03bb\u03b9\u03ba\u03bf\u03cd\u03c2 \u03c7\u03c1\u03ae\u03c3\u03c4\u03b5\u03c2\t\t<\/a>\n\t<\/div><p class=\"paragraph paragraph__color--dusty paragraph__align--center paragraph__size--default card-simple__paragraph\">\n\t\u03a0\u03b1\u03c1\u03b1\u03ba\u03bf\u03bb\u03bf\u03c5\u03b8\u03ae\u03c3\u03c4\u03b5 \u03c4\u03bf\u03c5\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ce\u03bd\u03c4\u03b1\u03c2 \u03c4\u03bf web cloud. \u0394\u03b9\u03b1\u03c4\u03af\u03b8\u03b5\u03c4\u03b1\u03b9 \u03b1\u03c0\u03b5\u03c5\u03b8\u03b5\u03af\u03b1\u03c2 \u03b1\u03c0\u03cc \u03b5\u03b4\u03ce.<\/p>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--60\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"faq\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t\u0395\u03c1\u03c9\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2 &amp; \u0391\u03c0\u03b1\u03bd\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2<\/h2>\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery  wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-faq__anchor\" id=\"faq\"><\/div>\n\n<div class=\"block-faq js-accordion\">\n\n\t\n\t<div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"true\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u03a0\u03b1\u03c1\u03ac\u03b3\u03b5\u03b9 \u03b7 Solplanet \u03c5\u03b2\u03c1\u03b9\u03b4\u03b9\u03ba\u03bf\u03cd\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2;\">\n\t\t\u03a0\u03b1\u03c1\u03ac\u03b3\u03b5\u03b9 \u03b7 Solplanet \u03c5\u03b2\u03c1\u03b9\u03b4\u03b9\u03ba\u03bf\u03cd\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"false\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u0392\u03b5\u03b2\u03b1\u03af\u03c9\u03c2! \u039a\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03ac\u03b6\u03bf\u03c5\u03bc\u03b5 \u03b1\u03c0\u03bf\u03b4\u03bf\u03c4\u03b9\u03ba\u03bf\u03cd\u03c2, \u03b1\u03be\u03b9\u03cc\u03c0\u03b9\u03c3\u03c4\u03bf\u03c5\u03c2 \u03ba\u03b1\u03b9 \u03b5\u03cd\u03c7\u03c1\u03b7\u03c3\u03c4\u03bf\u03c5\u03c2 \u03bc\u03bf\u03bd\u03bf\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03cd\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03c1\u03b9\u03c6\u03b1\u03c3\u03b9\u03ba\u03bf\u03cd\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2, \u03c6\u03c4\u03b9\u03b1\u03b3\u03bc\u03ad\u03bd\u03bf\u03c5\u03c2 \u03b5\u03b9\u03b4\u03b9\u03ba\u03ac \u03b3\u03b9\u03b1 \u03bf\u03b9\u03ba\u03b9\u03b1\u03ba\u03ad\u03c2, \u03b5\u03bc\u03c0\u03bf\u03c1\u03b9\u03ba\u03ad\u03c2 \u03ba\u03b1\u03b9 \u03b2\u03b9\u03bf\u03bc\u03b7\u03c7\u03b1\u03bd\u03b9\u03ba\u03ad\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2. \u0395\u03be\u03b5\u03c1\u03b5\u03c5\u03bd\u03ae\u03c3\u03c4\u03b5 \u03c4\u03bf\u03bd \u03c0\u03bb\u03ae\u03c1\u03b7 \u03ba\u03b1\u03c4\u03ac\u03bb\u03bf\u03b3\u03bf \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03c9\u03bd \u03bc\u03b1\u03c2  <a href=\"\/el\/products\/\" data-type=\"URL\">\u03b5\u03b4\u03ce<\/a>.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u03a0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c4\u03b5\u03cd\u03bf\u03bd\u03c4\u03b1\u03b9\u00a0 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b1\u03c0\u03cc \u03c5\u03c0\u03b5\u03c1\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2;\">\n\t\t\u03a0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c4\u03b5\u03cd\u03bf\u03bd\u03c4\u03b1\u03b9\u00a0 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b1\u03c0\u03cc \u03c5\u03c0\u03b5\u03c1\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u0397 \u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c3\u03af\u03b1 \u03b1\u03c0\u03cc \u03c5\u03c0\u03b5\u03c1\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2 \u03b5\u03af\u03bd\u03b1\u03b9 \u03ba\u03bf\u03b9\u03bd\u03ae \u03c0\u03b1\u03c1\u03ac\u03bc\u03b5\u03c4\u03c1\u03bf\u03c2 \u03c0\u03bf\u03c5 \u03b5\u03be\u03b5\u03c4\u03ac\u03b6\u03b5\u03c4\u03b1\u03b9 \u03ba\u03b1\u03c4\u03ac \u03c4\u03bf \u03c3\u03c7\u03b5\u03b4\u03b9\u03b1\u03c3\u03bc\u03cc \u03c4\u03bf\u03c5 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03ce\u03c3\u03c4\u03b5 \u03bd\u03b1 \u03c0\u03c1\u03bf\u03c6\u03c5\u03bb\u03ac\u03c3\u03c3\u03b5\u03b9 \u03c4\u03bf\u03bd \u03b5\u03be\u03bf\u03c0\u03bb\u03b9\u03c3\u03bc\u03cc \u03b1\u03c0\u03cc \u03b4\u03b9\u03b1\u03ba\u03c5\u03bc\u03ac\u03bd\u03c3\u03b5\u03b9\u03c2 \u03c4\u03bf\u03c5 \u03c1\u03b5\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2. \u03a4\u03b1 \u03b5\u03b9\u03b4\u03b9\u03ba\u03cc\u03c4\u03b5\u03c1\u03b1 \u03c7\u03b1\u03c1\u03b1\u03ba\u03c4\u03b7\u03c1\u03b9\u03c3\u03c4\u03b9\u03ba\u03ac \u03c0\u03bf\u03c5 \u03b4\u03b9\u03b1\u03b8\u03ad\u03c4\u03bf\u03c5\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c4\u03b7\u03c2 solplanet \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c3\u03af\u03b1 \u03b1\u03c0\u03cc \u03c5\u03c0\u03b5\u03c1\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2, \u03b5\u03be\u03b1\u03c1\u03c4\u03ce\u03bd\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03bf \u03ba\u03ac\u03b8\u03b5 \u03bc\u03bf\u03bd\u03c4\u03ad\u03bb\u03bf \u03ba\u03b1\u03b9 \u03c4\u03b9\u03c2 \u03c0\u03c1\u03bf\u03b4\u03b9\u03b1\u03b3\u03c1\u03b1\u03c6\u03ad\u03c2 \u03c4\u03bf\u03c5 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03bf\u03c2. \u03a3\u03b1\u03c2 \u03c3\u03c5\u03bc\u03b2\u03bf\u03c5\u03bb\u03b5\u03cd\u03bf\u03c5\u03bc\u03b5 \u03bd\u03b1 \u03b5\u03bb\u03ad\u03b3\u03be\u03b5\u03c4\u03b5 \u03c4\u03b1 \u03b1\u03bd\u03c4\u03af\u03c3\u03c4\u03bf\u03b9\u03c7\u03b1 \u03ad\u03b3\u03b3\u03c1\u03b1\u03c6\u03b1 \u03ba\u03b1\u03b9 \u03c4\u03b5\u03c7\u03bd\u03b9\u03ba\u03ac \u03b5\u03b3\u03c7\u03b5\u03b9\u03c1\u03af\u03b4\u03b9\u03b1, \u03ae \u03bd\u03b1 \u03b5\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03b5\u03c4\u03b5 \u03b1\u03c0\u03b5\u03c5\u03b8\u03b5\u03af\u03b1\u03c2 \u03bc\u03b5 \u03c4\u03b7 Solplanet \u03b3\u03b9\u03b1 \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03cc\u03c4\u03b5\u03c1\u03b5\u03c2 \u03bb\u03b5\u03c0\u03c4\u03bf\u03bc\u03ad\u03c1\u03b5\u03b9\u03b5\u03c2 \u03c3\u03c7\u03b5\u03c4\u03b9\u03ba\u03ac \u03bc\u03b5 \u03c4\u03b9\u03c2 \u03b4\u03c5\u03bd\u03b1\u03c4\u03cc\u03c4\u03b7\u03c4\u03b5\u03c2 \u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c3\u03af\u03b1\u03c2 \u03c5\u03c0\u03b5\u03c1\u03c4\u03ac\u03c3\u03b5\u03c9\u03bd \u03c4\u03c9\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03c9\u03bd \u03bc\u03b1\u03c2.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u03a4\u03b9 \u03b1\u03c0\u03cc\u03b4\u03bf\u03c3\u03b7 \u03ad\u03c7\u03bf\u03c5\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03c3\u03b5 \u03c5\u03c8\u03b7\u03bb\u03ad\u03c2 \u03b8\u03b5\u03c1\u03bc\u03bf\u03ba\u03c1\u03b1\u03c3\u03af\u03b5\u03c2 \u03c0\u03b5\u03c1\u03b9\u03b2\u03ac\u03bb\u03bb\u03bf\u03bd\u03c4\u03bf\u03c2;\">\n\t\t\u03a4\u03b9 \u03b1\u03c0\u03cc\u03b4\u03bf\u03c3\u03b7 \u03ad\u03c7\u03bf\u03c5\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03c3\u03b5 \u03c5\u03c8\u03b7\u03bb\u03ad\u03c2 \u03b8\u03b5\u03c1\u03bc\u03bf\u03ba\u03c1\u03b1\u03c3\u03af\u03b5\u03c2 \u03c0\u03b5\u03c1\u03b9\u03b2\u03ac\u03bb\u03bb\u03bf\u03bd\u03c4\u03bf\u03c2;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b1\u03bd\u03c4\u03b1\u03c0\u03bf\u03ba\u03c1\u03af\u03bd\u03bf\u03bd\u03c4\u03b1\u03b9 \u03c0\u03bf\u03bb\u03cd \u03ba\u03b1\u03bb\u03ac \u03c3\u03c4\u03b9\u03c2 \u03c5\u03c8\u03b7\u03bb\u03ad\u03c2 \u03b8\u03b5\u03c1\u03bc\u03bf\u03ba\u03c1\u03b1\u03c3\u03af\u03b5\u03c2 \u03c0\u03b5\u03c1\u03b9\u03b2\u03ac\u03bb\u03bb\u03bf\u03bd\u03c4\u03bf\u03c2. \u0395\u03bb\u03b1\u03c4\u03c4\u03ce\u03bd\u03bf\u03c5\u03bd \u03b1\u03c5\u03c4\u03cc\u03bc\u03b1\u03c4\u03b1 \u03c4\u03b7\u03bd \u03b9\u03c3\u03c7\u03cd \u03b5\u03be\u03cc\u03b4\u03bf\u03c5 \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03b1\u03c5\u03c4\u03bf\u03c0\u03c1\u03bf\u03c3\u03c4\u03b1\u03c4\u03b5\u03c5\u03b8\u03bf\u03cd\u03bd \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03c5\u03c0\u03b5\u03c1\u03b8\u03ad\u03c1\u03bc\u03b1\u03bd\u03c3\u03b7. \u03a3\u03c4\u03b9\u03c2 \u03bf\u03b4\u03b7\u03b3\u03af\u03b5\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2 \u03ba\u03b1\u03b9 \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03af\u03b1\u03c2 \u03c0\u03b5\u03c1\u03b9\u03bb\u03b1\u03bc\u03b2\u03ac\u03bd\u03bf\u03bd\u03c4\u03b1\u03b9 \u03c3\u03c5\u03b3\u03ba\u03b5\u03ba\u03c1\u03b9\u03bc\u03ad\u03bd\u03b5\u03c2 \u03ba\u03b1\u03bc\u03c0\u03cd\u03bb\u03b5\u03c2 \u03b5\u03bb\u03ac\u03c4\u03c4\u03c9\u03c3\u03b7\u03c2 \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03ba\u03ac\u03b8\u03b5 \u03bc\u03bf\u03bd\u03c4\u03ad\u03bb\u03bf \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u0394\u03b9\u03b1\u03b8\u03ad\u03c4\u03bf\u03c5\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c4\u03b7\u03c2 Solplanet \u03bb\u03cd\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03ad\u03bb\u03b5\u03b3\u03c7\u03bf \u03bc\u03b7\u03b4\u03b5\u03bd\u03b9\u03ba\u03ae\u03c2 \u03ad\u03b3\u03c7\u03c5\u03c3\u03b7\u03c2 \u03c3\u03c4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03bf;\">\n\t\t\u0394\u03b9\u03b1\u03b8\u03ad\u03c4\u03bf\u03c5\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03c4\u03b7\u03c2 Solplanet \u03bb\u03cd\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03ad\u03bb\u03b5\u03b3\u03c7\u03bf \u03bc\u03b7\u03b4\u03b5\u03bd\u03b9\u03ba\u03ae\u03c2 \u03ad\u03b3\u03c7\u03c5\u03c3\u03b7\u03c2 \u03c3\u03c4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03bf;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039d\u03b1\u03b9, \u03b4\u03b9\u03b1\u03b8\u03ad\u03c4\u03bf\u03c5\u03bd. \u038c\u03bb\u03bf\u03b9 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 \u03bc\u03b1\u03c2 \u03ad\u03c7\u03bf\u03c5\u03bd \u03c4\u03b7 \u03b4\u03c5\u03bd\u03b1\u03c4\u03cc\u03c4\u03b7\u03c4\u03b1 \u03bc\u03b7\u03b4\u03b5\u03bd\u03b9\u03ba\u03ae\u03c2 \u03ad\u03b3\u03c7\u03c5\u03c3\u03b7\u03c2 \u03c3\u03c4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03bf, \u03b5\u03c6\u03cc\u03c3\u03bf\u03bd \u03b7 \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03af\u03b1 \u03c1\u03c5\u03b8\u03bc\u03b9\u03c3\u03c4\u03b5\u03af \u03b1\u03c0\u03cc \u03c4\u03b7\u03bd \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ae. \u039c\u03c0\u03bf\u03c1\u03b5\u03af\u03c4\u03b5 \u03bd\u03b1 \u03b1\u03c0\u03bf\u03ba\u03c4\u03ae\u03c3\u03b5\u03c4\u03b5 \u03c0\u03c1\u03cc\u03c3\u03b2\u03b1\u03c3\u03b7 \u03c3\u03c4\u03b7\u03bd \u03c5\u03c0\u03b7\u03c1\u03b5\u03c3\u03af\u03b1 \u03b5\u03bb\u03ad\u03b3\u03c7\u03bf\u03c5 \u03ad\u03b3\u03c7\u03c5\u03c3\u03b7\u03c2 \u03bc\u03ad\u03c3\u03c9 \u03c4\u03bf\u03c5 \u03ad\u03be\u03c5\u03c0\u03bd\u03bf\u03c5 \u03bc\u03b5\u03c4\u03c1\u03b7\u03c4\u03ae \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c5\u03bd\u03b4\u03b5\u03b4\u03b5\u03bc\u03ad\u03bd\u03bf\u03c2 \u03c3\u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1.\u00a0<br><br>\u0393\u03b9\u03b1 \u03c0\u03b5\u03c1\u03b9\u03c3\u03c3\u03cc\u03c4\u03b5\u03c1\u03b5\u03c2 \u03c0\u03bb\u03b7\u03c1\u03bf\u03c6\u03bf\u03c1\u03af\u03b5\u03c2, \u03c0\u03b1\u03c1\u03b1\u03ba\u03b1\u03bb\u03bf\u03cd\u03bc\u03b5 \u03b1\u03c0\u03b5\u03c5\u03b8\u03c5\u03bd\u03b8\u03b5\u03af\u03c4\u03b5 \u03c3\u03c4\u03b1 \u03b5\u03b3\u03c7\u03b5\u03b9\u03c1\u03af\u03b4\u03b9\u03b1, \u03ae \u03b5\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03bc\u03b5 \u03c4\u03bf \u03c4\u03bc\u03ae\u03bc\u03b1 \u03c4\u03b5\u03c7\u03bd\u03b9\u03ba\u03ae\u03c2 \u03c5\u03c0\u03bf\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2 \u03c0\u03b5\u03bb\u03b1\u03c4\u03ce\u03bd.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u039c\u03c0\u03bf\u03c1\u03b5\u03af \u03b7 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ce\u03bd \u03c0\u03bf\u03c5 \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c5\u03bd\u03b4\u03b5\u03b4\u03b5\u03bc\u03ad\u03bd\u03b7 \u03bc\u03b5 \u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03c4\u03b7\u03c2 Solplanet \u03bd\u03b1 \u03c5\u03c0\u03b5\u03c1\u03b4\u03b9\u03b1\u03c3\u03c4\u03b1\u03c3\u03b9\u03bf\u03bb\u03bf\u03b3\u03b7\u03b8\u03b5\u03af;\u00a0\">\n\t\t\u039c\u03c0\u03bf\u03c1\u03b5\u03af \u03b7 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ce\u03bd \u03c0\u03bf\u03c5 \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c5\u03bd\u03b4\u03b5\u03b4\u03b5\u03bc\u03ad\u03bd\u03b7 \u03bc\u03b5 \u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03c4\u03b7\u03c2 Solplanet \u03bd\u03b1 \u03c5\u03c0\u03b5\u03c1\u03b4\u03b9\u03b1\u03c3\u03c4\u03b1\u03c3\u03b9\u03bf\u03bb\u03bf\u03b3\u03b7\u03b8\u03b5\u03af;\u00a0\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039d\u03b1\u03b9, \u03bc\u03c0\u03bf\u03c1\u03b5\u03af. \u0397 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ce\u03bd \u03bc\u03c0\u03bf\u03c1\u03b5\u03af \u03bd\u03b1 \u03c5\u03c0\u03b5\u03c1\u03b4\u03b9\u03b1\u03c3\u03c4\u03b1\u03c3\u03b9\u03bf\u03bb\u03bf\u03b3\u03b7\u03b8\u03b5\u03af \u03bc\u03ad\u03c7\u03c1\u03b9 \u03ba\u03b1\u03b9 150%, \u03b1\u03bd\u03ac\u03bb\u03bf\u03b3\u03b1 \u03bc\u03b5 \u03c4\u03b1 \u03b5\u03c0\u03af\u03c0\u03b5\u03b4\u03b1 \u03b1\u03ba\u03c4\u03b9\u03bd\u03bf\u03b2\u03bf\u03bb\u03af\u03b1\u03c2 \u03c0\u03bf\u03c5 \u03bb\u03b1\u03bc\u03b2\u03ac\u03bd\u03bf\u03c5\u03bd \u03c4\u03b1 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ac \u03c0\u03bb\u03b1\u03af\u03c3\u03b9\u03b1 \u03bb\u03cc\u03b3\u03c9 \u03ba\u03bb\u03af\u03c3\u03b7\u03c2 \u03ba\u03b1\u03b9 \u03c0\u03c1\u03bf\u03c3\u03b1\u03bd\u03b1\u03c4\u03bf\u03bb\u03b9\u03c3\u03bc\u03bf\u03cd.\u00a0 \u03a3\u03b7\u03bc\u03b5\u03b9\u03ce\u03c3\u03c4\u03b5 \u03cc\u03bc\u03c9\u03c2 \u03cc\u03c4\u03b9 \u03b7 \u03c5\u03c0\u03b5\u03c1\u03b2\u03bf\u03bb\u03b9\u03ba\u03ae \u03c5\u03c0\u03b5\u03c1\u03b4\u03b9\u03b1\u03c3\u03c4\u03b1\u03c3\u03b9\u03bf\u03bb\u03cc\u03b3\u03b7\u03c3\u03b7 \u03bc\u03c0\u03bf\u03c1\u03b5\u03af \u03bd\u03b1 \u03bf\u03b4\u03b7\u03b3\u03ae\u03c3\u03b5\u03b9 \u03c3\u03b5 \u03ac\u03c3\u03ba\u03bf\u03c0\u03b7 \u03c3\u03c0\u03b1\u03c4\u03ac\u03bb\u03b7 \u03c7\u03c1\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd \u03ba\u03b1\u03b9 \u03b1\u03c1\u03bd\u03b7\u03c4\u03b9\u03ba\u03cc \u03b1\u03bd\u03c4\u03af\u03ba\u03c4\u03c5\u03c0\u03bf \u03c3\u03c4\u03b7\u03bd \u03b1\u03be\u03b9\u03bf\u03c0\u03b9\u03c3\u03c4\u03af\u03b1 \u03c4\u03bf\u03c5 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1. \u0391\u03bd \u03ad\u03c7\u03b5\u03c4\u03b5 \u03b1\u03c0\u03bf\u03c1\u03af\u03b5\u03c2 \u03c3\u03c7\u03b5\u03c4\u03b9\u03ba\u03ac \u03bc\u03b5 \u03c4\u03b7\u03bd \u03c5\u03c0\u03b5\u03c1\u03b4\u03b9\u03b1\u03c3\u03c4\u03b1\u03c3\u03b9\u03bf\u03bb\u03cc\u03b3\u03b7\u03c3\u03b7 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ae\u03c2 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1\u03c2, \u03c0\u03b1\u03c1\u03b1\u03ba\u03b1\u03bb\u03bf\u03cd\u03bc\u03b5 \u03b5\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03c4\u03bf \u03b3\u03c1\u03b1\u03c6\u03b5\u03af\u03bf \u03c4\u03b7\u03c2\u00a0 Solplanet \u03c4\u03b7\u03c2 \u03c0\u03b5\u03c1\u03b9\u03bf\u03c7\u03ae\u03c2 \u03c3\u03b1\u03c2.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u039c\u03c0\u03bf\u03c1\u03b5\u03af \u03ba\u03ac\u03c0\u03bf\u03b9\u03bf\u03c2 \u03bd\u03b1 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ae\u03c3\u03b5\u03b9 \u03b5\u03cd\u03ba\u03b1\u03bc\u03c0\u03c4\u03b1 \u03c0\u03ac\u03bd\u03b5\u03bb \u03b3\u03b9\u03b1 \u03c4\u03bf\u03c5\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet;\u00a0\">\n\t\t\u039c\u03c0\u03bf\u03c1\u03b5\u03af \u03ba\u03ac\u03c0\u03bf\u03b9\u03bf\u03c2 \u03bd\u03b1 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ae\u03c3\u03b5\u03b9 \u03b5\u03cd\u03ba\u03b1\u03bc\u03c0\u03c4\u03b1 \u03c0\u03ac\u03bd\u03b5\u03bb \u03b3\u03b9\u03b1 \u03c4\u03bf\u03c5\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet;\u00a0\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03bc\u03c0\u03bf\u03c1\u03bf\u03cd\u03bd \u03bd\u03b1 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03b7\u03b8\u03bf\u03cd\u03bd \u03bc\u03b5 \u03b5\u03cd\u03ba\u03b1\u03bc\u03c0\u03c4\u03b1 \u03b7\u03bb\u03b9\u03b1\u03ba\u03ac \u03c0\u03ac\u03bd\u03b5\u03bb, \u03b1\u03c5\u03c4\u03cc \u03cc\u03bc\u03c9\u03c2 \u03b8\u03b1 \u03ae\u03c4\u03b1\u03bd \u03cc\u03bc\u03c9\u03c2 \u03bc\u03b9\u03b1 \u03c0\u03bf\u03bb\u03cd\u00a0 \u03c3\u03c0\u03ac\u03bd\u03b9\u03b1 \u03c0\u03b5\u03c1\u03af\u03c0\u03c4\u03c9\u03c3\u03b7 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2. \u03a4\u03b1 \u03b5\u03cd\u03ba\u03b1\u03bc\u03c0\u03c4\u03b1 \u03b7\u03bb\u03b9\u03b1\u03ba\u03ac \u03c0\u03ac\u03bd\u03b5\u03bb \u03c3\u03c5\u03bd\u03ae\u03b8\u03c9\u03c2 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03bf\u03cd\u03bd\u03c4\u03b1\u03b9 \u03c3\u03b5 \u03c6\u03bf\u03c1\u03b7\u03c4\u03bf\u03cd\u03c2 \u03c3\u03c4\u03b1\u03b8\u03bc\u03bf\u03cd\u03c2 \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2. <br><br>\u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c4\u03b1\u03b8\u03b5\u03c1\u03bf\u03af \u03ba\u03b1\u03b9 \u03ad\u03c7\u03bf\u03c5\u03bd \u03c3\u03c7\u03b5\u03b4\u03b9\u03b1\u03c3\u03c4\u03b5\u03af \u03b3\u03b9\u03b1 \u03c0\u03b1\u03c1\u03b1\u03b4\u03bf\u03c3\u03b9\u03b1\u03ba\u03ad\u03c2 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b5\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ce\u03bd \u03c3\u03b5 \u03bf\u03b9\u03ba\u03b9\u03b1\u03ba\u03ad\u03c2, \u03b5\u03bc\u03c0\u03bf\u03c1\u03b9\u03ba\u03ad\u03c2 \u03ba\u03b1\u03b9 \u03b2\u03b9\u03bf\u03bc\u03b7\u03c7\u03b1\u03bd\u03b9\u03ba\u03ad\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03b1\u03c3\u03c4\u03ac\u03c3\u03b5\u03b9\u03c2.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u039c\u03c0\u03bf\u03c1\u03bf\u03cd\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03bd\u03b1 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03b7\u03b8\u03bf\u03cd\u03bd \u03c3\u03b5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03b1 \u03b5\u03ba\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5 \u03c0\u03bf\u03c5 \u03c0\u03b5\u03c1\u03b9\u03bb\u03b1\u03bc\u03b2\u03ac\u03bd\u03bf\u03c5\u03bd \u03b3\u03b5\u03bd\u03bd\u03ae\u03c4\u03c1\u03b9\u03b5\u03c2 \u03bd\u03c4\u03af\u03b6\u03b5\u03bb;\u00a0z\">\n\t\t\u039c\u03c0\u03bf\u03c1\u03bf\u03cd\u03bd \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03bd\u03b1 \u03c7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03b7\u03b8\u03bf\u03cd\u03bd \u03c3\u03b5 \u03c3\u03c5\u03c3\u03c4\u03ae\u03bc\u03b1\u03c4\u03b1 \u03b5\u03ba\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5 \u03c0\u03bf\u03c5 \u03c0\u03b5\u03c1\u03b9\u03bb\u03b1\u03bc\u03b2\u03ac\u03bd\u03bf\u03c5\u03bd \u03b3\u03b5\u03bd\u03bd\u03ae\u03c4\u03c1\u03b9\u03b5\u03c2 \u03bd\u03c4\u03af\u03b6\u03b5\u03bb;\u00a0z\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u038c\u03c7\u03b9, \u03b4\u03b5\u03bd \u03bc\u03c0\u03bf\u03c1\u03bf\u03cd\u03bd. \u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c7\u03b5\u03b4\u03b9\u03b1\u03c3\u03bc\u03ad\u03bd\u03bf\u03b9 \u03bd\u03b1 \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03bf\u03cd\u03bd \u03b5\u03bd\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5. \u0397 \u03c0\u03bb\u03b5\u03c5\u03c1\u03ac AC (\u03b5\u03bd\u03b1\u03bb\u03bb\u03b1\u03c3\u03c3\u03cc\u03bc\u03b5\u03bd\u03bf\u03c5) \u03c1\u03b5\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2 \u03c4\u03bf\u03c5 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03b8\u03b1 \u03c0\u03c1\u03ad\u03c0\u03b5\u03b9 \u03bd\u03b1 \u03b5\u03af\u03bd\u03b1\u03b9 \u03c0\u03ac\u03bd\u03c4\u03b1 \u03c3\u03c5\u03bd\u03b4\u03b5\u03b4\u03b5\u03bc\u03ad\u03bd\u03b7 \u03bc\u03b5 \u03c4\u03bf \u03b4\u03af\u03ba\u03c4\u03c5\u03bf. \u0394\u03b5\u03bd \u03c5\u03c0\u03ac\u03c1\u03c7\u03bf\u03c5\u03bd \u03c1\u03c5\u03b8\u03bc\u03af\u03c3\u03b5\u03b9\u03c2 \u03c0\u03bf\u03c5 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03c4\u03c1\u03ad\u03c0\u03bf\u03c5\u03bd \u03c3\u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03bd\u03b1 \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03b5\u03af \u201c\u03b5\u03ba\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5\u201d \u03ae \u03c3\u03b5 \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03af\u03b1 \u201c\u03bd\u03b7\u03c3\u03af\u03b4\u03b1\u03c2\u201d. \u0397 Solplanet \u03b4\u03b5\u03bd \u03bc\u03c0\u03bf\u03c1\u03b5\u03af \u03bd\u03b1 \u03b5\u03b3\u03b3\u03c5\u03b7\u03b8\u03b5\u03af \u03c4\u03b7 \u03c3\u03c9\u03c3\u03c4\u03ae \u03bb\u03b5\u03b9\u03c4\u03bf\u03c5\u03c1\u03b3\u03af\u03b1 \u03c3\u03b5 \u03b5\u03c6\u03b1\u03c1\u03bc\u03bf\u03b3\u03ad\u03c2 \u03b5\u03ba\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5 \u03ba\u03b1\u03b9 \u03b4\u03b5\u03bd \u03b5\u03b3\u03b3\u03c5\u03ac\u03c4\u03b1\u03b9 \u03b3\u03b9\u03b1 \u03ba\u03b1\u03bc\u03af\u03b1 \u03b6\u03b7\u03bc\u03af\u03b1 \u03c0\u03bf\u03c5 \u03c0\u03c1\u03bf\u03ba\u03bb\u03ae\u03b8\u03b7\u03ba\u03b5 \u03c3\u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 (\u03ae \u03c4\u03bf\u03c5\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2) \u03ae \u03c4\u03bf\u03bd \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03cc \u03c3\u03c4\u03b1\u03b8\u03bc\u03cc \u03bb\u03cc\u03b3\u03c9 \u03c4\u03b7\u03c2 \u03c7\u03c1\u03ae\u03c3\u03b7\u03c2 \u03b5\u03ba\u03c4\u03cc\u03c2 \u03b4\u03b9\u03ba\u03c4\u03cd\u03bf\u03c5.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03b9 \u03ae \u03bc\u03b7-\u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03b9;\">\n\t\t\u039f\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03b9 \u03ae \u03bc\u03b7-\u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03b9;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u0397 Solplanet \u03c0\u03b1\u03c1\u03ac\u03b3\u03b5\u03b9 \u03bc\u03cc\u03bd\u03bf \u03bc\u03b7-\u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03c5\u03c2 (\u03c7\u03c9\u03c1\u03af\u03c2 \u03bc\u03b5\u03c4\u03b1\u03c3\u03c7\u03b7\u03bc\u03b1\u03c4\u03b9\u03c3\u03c4\u03ae) \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2. \u039f \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1\u03c2 \u03c7\u03c9\u03c1\u03af\u03c2 \u03bc\u03b5\u03c4\u03b1\u03c3\u03c7\u03b7\u03bc\u03b1\u03c4\u03b9\u03c3\u03c4\u03ae \u03b5\u03af\u03bd\u03b1\u03b9 \u03bf \u03c0\u03b9\u03bf \u03ba\u03bf\u03b9\u03bd\u03cc\u03c2 \u03c3\u03c4\u03b7\u03bd \u03bf\u03b9\u03ba\u03b9\u03b1\u03ba\u03ae \u03ba\u03b1\u03b9 \u03b5\u03bc\u03c0\u03bf\u03c1\u03b9\u03ba\u03ae \u03b1\u03b3\u03bf\u03c1\u03ac, \u03b3\u03b9\u03b1\u03c4\u03af \u03c3\u03c5\u03bd\u03ae\u03b8\u03c9\u03c2 \u03b4\u03b9\u03b1\u03b8\u03ad\u03c4\u03b5\u03b9 \u03c4\u03b7\u03bd \u03c5\u03c8\u03b7\u03bb\u03cc\u03c4\u03b5\u03c1\u03b7 \u03b1\u03c0\u03cc\u03b4\u03bf\u03c3\u03b7, \u03c4\u03bf \u03c7\u03b1\u03bc\u03b7\u03bb\u03cc\u03c4\u03b5\u03c1\u03bf \u03ba\u03cc\u03c3\u03c4\u03bf\u03c2, \u03c4\u03bf \u03bc\u03b9\u03ba\u03c1\u03cc\u03c4\u03b5\u03c1\u03bf \u03bc\u03ad\u03b3\u03b5\u03b8\u03bf\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03bf \u03c7\u03b1\u03bc\u03b7\u03bb\u03cc\u03c4\u03b5\u03c1\u03bf \u03b2\u03ac\u03c1\u03bf\u03c2 \u03c3\u03b5 \u03c3\u03cd\u03b3\u03ba\u03c1\u03b9\u03c3\u03b7 \u03bc\u03b5\u00a0 \u03c4\u03bf\u03c5\u03c2 \u03b1\u03c0\u03bf\u03bc\u03bf\u03bd\u03c9\u03bc\u03ad\u03bd\u03bf\u03c5\u03c2 (\u03bc\u03b5 \u03bc\u03b5\u03c4\u03b1\u03c3\u03c7\u03b7\u03bc\u03b1\u03c4\u03b9\u03c3\u03c4\u03ae) \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2.\u00a0<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u0395\u03af\u03bd\u03b1\u03b9 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03be\u03bf\u03c0\u03bb\u03b9\u03c3\u03bc\u03ad\u03bd\u03bf\u03b9 \u03bc\u03b5 \u03b4\u03b9\u03b1\u03ba\u03cc\u03c0\u03c4\u03b7 DC (\u03c3\u03c5\u03bd\u03b5\u03c7\u03bf\u03cd\u03c2 \u03c1\u03b5\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2);\u00a0\">\n\t\t\u0395\u03af\u03bd\u03b1\u03b9 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03be\u03bf\u03c0\u03bb\u03b9\u03c3\u03bc\u03ad\u03bd\u03bf\u03b9 \u03bc\u03b5 \u03b4\u03b9\u03b1\u03ba\u03cc\u03c0\u03c4\u03b7 DC (\u03c3\u03c5\u03bd\u03b5\u03c7\u03bf\u03cd\u03c2 \u03c1\u03b5\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2);\u00a0\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039d\u03b1\u03b9, \u03cc\u03bb\u03bf\u03b9 \u03bf\u03b9 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03b5\u03af\u03c2 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03b5\u03be\u03bf\u03c0\u03bb\u03b9\u03c3\u03bc\u03ad\u03bd\u03bf\u03b9 \u03bc\u03b5 \u03b4\u03b9\u03b1\u03ba\u03cc\u03c0\u03c4\u03b7 DC \u03b3\u03b9\u03b1 \u03c4\u03b7\u03bd \u03bf\u03bc\u03b1\u03bb\u03ae \u03ba\u03b1\u03b9 \u03b1\u03b4\u03b9\u03ac\u03ba\u03bf\u03c0\u03b7 \u03b4\u03b9\u03b1\u03bd\u03bf\u03bc\u03ae \u03c1\u03b5\u03cd\u03bc\u03b1\u03c4\u03bf\u03c2.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><div class=\"accordion  accordion--type-full accordion--theme-dark js-accordion-parent\" data-accordion-opened=\"false\">\n\t<button class=\"accordion__trigger js-accordion-trigger gtm_question_el\" aria-label=\"\u03a0\u03ce\u03c2 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03bb\u03ad\u03be\u03c9 \u03c4\u03bf \u03c3\u03c9\u03c3\u03c4\u03cc \u03bc\u03ad\u03b3\u03b5\u03b8\u03bf\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1;\">\n\t\t\u03a0\u03ce\u03c2 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03bb\u03ad\u03be\u03c9 \u03c4\u03bf \u03c3\u03c9\u03c3\u03c4\u03cc \u03bc\u03ad\u03b3\u03b5\u03b8\u03bf\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1;\t\t<div class=\"accordion__icon\" aria-hidden=\"true\">\n\t\t\t<svg width=\"30\" height=\"30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n\t\t\t\t<g transform=\"translate(1 1)\" fill=\"none\" fill-rule=\"evenodd\">\n\t\t\t\t\t<circle stroke=\"#979797\" cx=\"14\" cy=\"14\" r=\"14\" \/>\n\t\t\t\t\t<g stroke=\"#717171\" stroke-linecap=\"square\">\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318M13.969 7v14\" class=\"accordion__icon--plus\" \/>\n\t\t\t\t\t\t<path d=\"M6.341 14h14.318\" class=\"accordion__icon--minus\" \/>\n\t\t\t\t\t<\/g>\n\t\t\t\t<\/g>\n\t\t\t<\/svg>\n\t\t<\/div>\n\t<\/button>\n\t<section class=\"accordion__panel js-accordion-panel\" aria-hidden=\"true\">\n\t\t<div class=\"accordion__content\">\n\t\t\t<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039c\u03b5 \u03c0\u03bf\u03bb\u03cd \u03b1\u03c0\u03bb\u03ac \u03bb\u03cc\u03b3\u03b9\u03b1, \u03b8\u03b1 \u03c0\u03c1\u03ad\u03c0\u03b5\u03b9 \u03bd\u03b1 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03c3\u03b5\u03c4\u03b5 \u03c4\u03bf\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 \u03c3\u03b1\u03c2 \u03bc\u03b5 \u03c4\u03b7\u03bd \u0399\u03c3\u03c7\u03cd(W) \u03c4\u03b7\u03c2 \u03c6\u03c9\u03c4\u03bf\u03b2\u03bf\u03bb\u03c4\u03b1\u03ca\u03ba\u03ae\u03c2 \u03c3\u03b1\u03c2 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1\u03c2. \u0393\u03b9\u03b1 \u03c0\u03b1\u03c1\u03ac\u03b4\u03b5\u03b9\u03b3\u03bc\u03b1, \u03b1\u03bd \u03ad\u03c7\u03b5\u03c4\u03b5 \u03bc\u03b9\u03b1 \u03c3\u03c5\u03c3\u03c4\u03bf\u03b9\u03c7\u03af\u03b1 \u03a6\/\u0392 3000 Watt, \u03b8\u03b1 \u03c7\u03c1\u03b5\u03b9\u03b1\u03c3\u03c4\u03b5\u03af\u03c4\u03b5 \u03ad\u03bd\u03b1\u03bd \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1 3000 Watt \u03c4\u03bf\u03c5\u03bb\u03ac\u03c7\u03b9\u03c3\u03c4\u03bf\u03bd. \u0398\u03b1 \u03c0\u03c1\u03ad\u03c0\u03b5\u03b9 \u03b5\u03c0\u03af\u03c3\u03b7\u03c2 \u03bd\u03b1 \u03bb\u03ac\u03b2\u03b5\u03c4\u03b5 \u03c5\u03c0\u03cc\u03c8\u03b7 \u03c0\u03c1\u03ac\u03b3\u03bc\u03b1\u03c4\u03b1 \u03cc\u03c0\u03c9\u03c2 \u03c4\u03b1 \u03c5\u03c0\u03cc\u03bb\u03bf\u03b9\u03c0\u03b1 \u03c7\u03b1\u03c1\u03b1\u03ba\u03c4\u03b7\u03c1\u03b9\u03c3\u03c4\u03b9\u03ba\u03ac \u03c4\u03c9\u03bd \u03c0\u03bb\u03b1\u03b9\u03c3\u03af\u03c9\u03bd, \u03c4\u03bf \u03bc\u03ad\u03b3\u03b9\u03c3\u03c4\u03bf \u03bc\u03ad\u03b3\u03b5\u03b8\u03bf\u03c2 \u03c4\u03b7\u03c2 \u03b5\u03b3\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2, \u03b1\u03ba\u03cc\u03bc\u03b1 \u03ba\u03b1\u03b9 \u03c4\u03b7\u03bd \u03b3\u03b5\u03c9\u03b3\u03c1\u03b1\u03c6\u03b9\u03ba\u03ae \u03c3\u03b1\u03c2 \u03b8\u03ad\u03c3\u03b7. \u038c\u03bc\u03c9\u03c2, \u03bc\u03b7\u03bd \u03b1\u03bd\u03b7\u03c3\u03c5\u03c7\u03b5\u03af\u03c4\u03b5, \u03b4\u03b5\u03bd \u03b5\u03af\u03bd\u03b1\u03b9 \u03c4\u03cc\u03c3\u03bf \u03c0\u03b5\u03c1\u03af\u03c0\u03bb\u03bf\u03ba\u03bf \u03cc\u03c3\u03bf \u03c6\u03b1\u03af\u03bd\u03b5\u03c4\u03b1\u03b9.<br><br>\u0395\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03bc\u03b5 \u03c4\u03b7\u03bd \u03bf\u03bc\u03ac\u03b4\u03b1 \u03c5\u03c0\u03bf\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7\u03c2 \u03c0\u03b5\u03bb\u03b1\u03c4\u03ce\u03bd \u03bc\u03b1\u03c2, \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03c3\u03b1\u03c2 \u03b2\u03bf\u03b7\u03b8\u03ae\u03c3\u03b5\u03b9 \u03bd\u03b1 \u03b1\u03c0\u03bf\u03c6\u03b1\u03c3\u03af\u03c3\u03b5\u03c4\u03b5 \u03c0\u03bf\u03b9o\u03c2 \u03b1\u03bd\u03c4\u03b9\u03c3\u03c4\u03c1\u03bf\u03c6\u03ad\u03b1\u03c2 Solplanet \u03c3\u03b1\u03c2 \u03c4\u03b1\u03b9\u03c1\u03b9\u03ac\u03b6\u03b5\u03b9 \u03ba\u03b1\u03bb\u03cd\u03c4\u03b5\u03c1\u03b1.<\/p>\t<\/div>\n\t\t<\/div>\n\t<\/section>\n<\/div><\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper wrapper__bg-color--gallery wrapper__spacing-top-large--80 wrapper__spacing-bottom-large--120\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/el\/questions-answers\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0395\u03c0\u03b9\u03c3\u03ba\u03b5\u03c6\u03b8\u03b5\u03af\u03c4\u03b5 \u03c4\u03bf \u03c0\u03b5\u03b4\u03af\u03bf \u03bc\u03b5 \u03c4\u03b9\u03c2 \u03c3\u03c5\u03c7\u03bd\u03ad\u03c2 \u03b5\u03c1\u03c9\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2 (FAQ)\" aria-label=\"\">\n\t\t\t\u0395\u03c0\u03b9\u03c3\u03ba\u03b5\u03c6\u03b8\u03b5\u03af\u03c4\u03b5 \u03c4\u03bf \u03c0\u03b5\u03b4\u03af\u03bf \u03bc\u03b5 \u03c4\u03b9\u03c2 \u03c3\u03c5\u03c7\u03bd\u03ad\u03c2 \u03b5\u03c1\u03c9\u03c4\u03ae\u03c3\u03b5\u03b9\u03c2 (FAQ)\t\t<\/a>\n\t<\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--120 wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"warranty\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-heading block-heading--with-image block-heading--center-mobile\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--default block-heading__heading\">\n\t\u039f\u03b9 \u03ba\u03bf\u03c1\u03c5\u03c6\u03b1\u03af\u03b5\u03c2 \u03b5\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03c4\u03c9\u03bd \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03c9\u03bd \u03b7\u03bb\u03b9\u03b1\u03ba\u03ae\u03c2 \u03b5\u03bd\u03ad\u03c1\u03b3\u03b5\u03b9\u03b1\u03c2 \u03c4\u03b7\u03c2 Solplanet<\/h2>\t<img src=\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/10\/Screenshot-2020-10-23-at-12.49.24.png\" class=\"image block-heading__image\" \/><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--80\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"wrapper__container wrapper__container-width-large--default wrapper__gutter-large--default wrapper__gutter-tablet--small\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-columns js-block-columns block-columns__gutter-large--big block-columns__vertical-spacing-large--big\">\n\t\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\u03a0\u03bb\u03b7\u03c1\u03bf\u03c6\u03bf\u03c1\u03af\u03b5\u03c2 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u03a0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03bf\u03c5\u03bc\u03b5 \u03c3\u03c4\u03b1\u03b8\u03b5\u03c1\u03ae \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7 \u03b3\u03b9\u03b1 \u03ad\u03c9\u03c2 \u03ba\u03b1\u03b9 6 \u03c7\u03c1\u03cc\u03bd\u03b9\u03b1 \u03c0\u03ad\u03c1\u03b1\u03bd \u03c4\u03b7\u03c2 \u03bd\u03cc\u03bc\u03b9\u03bc\u03b7\u03c2 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2 \u03c0\u03bf\u03c5 \u03c0\u03c1\u03bf\u03c3\u03c6\u03ad\u03c1\u03b5\u03c4\u03b1\u03b9 \u03b1\u03c0\u03cc \u03c4\u03bf\u03bd \u03ad\u03bc\u03c0\u03bf\u03c1\u03bf \u03c7\u03bf\u03bd\u03b4\u03c1\u03b9\u03ba\u03ae\u03c2 \u03ae \u03bb\u03b9\u03b1\u03bd\u03b9\u03ba\u03ae\u03c2. \u03a0\u03b1\u03c1\u03cc\u03bb\u03b1 \u03b1\u03c5\u03c4\u03ac, \u03b5\u03c0\u03b5\u03b9\u03b4\u03ae \u03b7 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03b4\u03b9\u03b5\u03b8\u03bd\u03ae\u03c2 \u03b5\u03c4\u03b1\u03b9\u03c1\u03b5\u03af\u03b1, \u03bf\u03b9 \u03b5\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03b1\u03bd\u03b1\u03bc\u03ad\u03bd\u03b5\u03c4\u03b1\u03b9 \u03bd\u03b1 \u03b4\u03b9\u03b1\u03c6\u03ad\u03c1\u03bf\u03c5\u03bd \u03b1\u03bd\u03ac \u03c0\u03b5\u03c1\u03b9\u03bf\u03c7\u03ae.\u00a0\u00a0<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/S-PM21-006-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V2.0.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0394\u03b9\u03b5\u03b8\u03bd\u03b5\u03af\u03c2 \u03b5\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0394\u03b9\u03b5\u03b8\u03bd\u03b5\u03af\u03c2 \u03b5\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2024\/01\/s-pm21-009-battery-factory-quality-warranty-terms-for-overseas-territory-of-aiswei_v1.2.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03bc\u03c0\u03b1\u03c4\u03b1\u03c1\u03af\u03b1\u03c2\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03bc\u03c0\u03b1\u03c4\u03b1\u03c1\u03af\u03b1\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large---10 wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/S-NB21-003-EV-Charger-Factory-Quality-Warranty-Terms-for-Overseas-Territory-of-AISWEI_V1.4.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03c6\u03bf\u03c1\u03c4\u03b9\u03c3\u03c4\u03ce\u03bd \u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03ce\u03bd \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03c6\u03bf\u03c1\u03c4\u03b9\u03c3\u03c4\u03ce\u03bd \u03b7\u03bb\u03b5\u03ba\u03c4\u03c1\u03b9\u03ba\u03ce\u03bd \u03bf\u03c7\u03b7\u03bc\u03ac\u03c4\u03c9\u03bd\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large---1 wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/solplanet.net\/wp-content\/uploads\/2023\/09\/Heat-pump_warranty-terms_EN_0923.pdf\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03b1\u03bd\u03c4\u03bb\u03b9\u03ce\u03bd \u03b8\u03b5\u03c1\u03bc\u03cc\u03c4\u03b7\u03c4\u03b1\u03c2\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0395\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03b9\u03c2 \u03b1\u03bd\u03c4\u03bb\u03b9\u03ce\u03bd \u03b8\u03b5\u03c1\u03bc\u03cc\u03c4\u03b7\u03c4\u03b1\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\u039a\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u03a7\u03c1\u03b5\u03b9\u03ac\u03b6\u03b5\u03c4\u03b1\u03b9 \u03bd\u03b1 \u03b5\u03bb\u03ad\u03b3\u03be\u03b5\u03c4\u03b5 \u03c4\u03b7\u03bd \u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7 \u03c4\u03b7\u03c2 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03ae\u03c2 \u03c3\u03b1\u03c2; \u039a\u03b1\u03bd\u03ad\u03bd\u03b1 \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1. \u039a\u03ac\u03bd\u03c4\u03b5 \u03ba\u03bb\u03b9\u03ba \u03c3\u03c4\u03bf \u03c0\u03b1\u03c1\u03b1\u03ba\u03ac\u03c4\u03c9 \u03c0\u03b5\u03b4\u03af\u03bf \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03bc\u03b5\u03c4\u03b1\u03c6\u03b5\u03c1\u03b8\u03b5\u03af\u03c4\u03b5 \u03c3\u03c4\u03b7 \u03c3\u03b5\u03bb\u03af\u03b4\u03b1 \u03b5\u03bb\u03ad\u03b3\u03c7\u03bf\u03c5 \u03b5\u03b3\u03b3\u03c5\u03ae\u03c3\u03b5\u03c9\u03bd, \u03cc\u03c0\u03bf\u03c5 \u03b8\u03b1 \u03bc\u03c0\u03bf\u03c1\u03ad\u03c3\u03b5\u03c4\u03b5 \u03bd\u03b1 \u03b2\u03c1\u03b5\u03af\u03c4\u03b5 \u03c0\u03bb\u03b7\u03c1\u03bf\u03c6\u03bf\u03c1\u03af\u03b5\u03c2 \u03b3\u03b9\u03b1 \u03c4\u03bf \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd \u03c3\u03b1\u03c2 \u03bc\u03b5 \u03c4\u03bf\u03bd \u03c3\u03b5\u03b9\u03c1\u03b9\u03b1\u03ba\u03cc \u03b1\u03c1\u03b9\u03b8\u03bc\u03cc \u03c4\u03bf\u03c5.\u00a0<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\/warrantySearch\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0395\u03bb\u03ad\u03b3\u03be\u03c4\u03b5 \u03c4\u03b7\u03bd \u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0395\u03bb\u03ad\u03b3\u03be\u03c4\u03b5 \u03c4\u03b7\u03bd \u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n\n\n<div class=\"block-column block-column__width-large--4 block-column__width-tablet--12 \">\n\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--30\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--shaft heading__size--small block-heading__heading\">\n\t\u0395\u03c0\u03ad\u03ba\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--10\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u0398\u03ad\u03bb\u03b5\u03c4\u03b5 \u03bd\u03b1 \u03b5\u03c0\u03b5\u03ba\u03c4\u03b5\u03af\u03bd\u03b5\u03c4\u03b5 \u03c4\u03b7\u03bd \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03ae \u03c3\u03b1\u03c2; \u039a\u03ac\u03bd\u03c4\u03b5 \u03ba\u03bb\u03b9\u03ba \u03c3\u03c4\u03bf \u03c0\u03b1\u03c1\u03b1\u03ba\u03ac\u03c4\u03c9 \u03c0\u03b5\u03b4\u03af\u03bf \u03ba\u03b1\u03b9 \u03c3\u03c5\u03bd\u03b4\u03b5\u03b8\u03b5\u03af\u03c4\u03b5, \u03ae \u03b4\u03b7\u03bc\u03b9\u03bf\u03c5\u03c1\u03b3\u03ae\u03c3\u03c4\u03b5 \u03ad\u03bd\u03b1\u03bd \u03bb\u03bf\u03b3\u03b1\u03c1\u03b9\u03b1\u03c3\u03bc\u03cc. \u0395\u03c6\u03cc\u03c3\u03bf\u03bd \u03b4\u03b7\u03bc\u03b9\u03bf\u03c5\u03c1\u03b3\u03ae\u03c3\u03b5\u03c4\u03b5 \u03bb\u03bf\u03b3\u03b1\u03c1\u03b9\u03b1\u03c3\u03bc\u03cc, \u03b8\u03b1 \u03bc\u03c0\u03bf\u03c1\u03b5\u03af\u03c4\u03b5 \u03bd\u03b1 \u03b1\u03b3\u03bf\u03c1\u03ac\u03c3\u03b5\u03c4\u03b5 \u03b5\u03c0\u03ad\u03ba\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2 \u03c0\u03c1\u03bf\u03c3\u03b1\u03c1\u03bc\u03bf\u03c3\u03bc\u03ad\u03bd\u03b7 \u03c3\u03c4\u03bf \u03ba\u03cc\u03c3\u03c4\u03bf\u03c2 \u03ba\u03b1\u03b9 \u03c4\u03b7 \u03b4\u03b9\u03ac\u03c1\u03ba\u03b5\u03b9\u03b1 \u03c0\u03bf\u03c5 \u03c3\u03b1\u03c2 \u03c4\u03b1\u03b9\u03c1\u03b9\u03ac\u03b6\u03b5\u03b9.<br><\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/warranty-solplanet.aiswei-tech.com\/#\/en\" class=\"btn btn__color--alto btn__size--default btn__size-width--default \" id=\"\" title=\"\u0391\u03c0\u03bf\u03ba\u03c4\u03ae\u03c3\u03c4\u03b5 \u03c4\u03b7\u03bd \u03b5\u03c0\u03ad\u03ba\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2\" aria-label=\"\" target=\"_blank\" rel=\"noopener noreferrer\">\n\t\t\t\u0391\u03c0\u03bf\u03ba\u03c4\u03ae\u03c3\u03c4\u03b5 \u03c4\u03b7\u03bd \u03b5\u03c0\u03ad\u03ba\u03c4\u03b1\u03c3\u03b7 \u03b5\u03b3\u03b3\u03cd\u03b7\u03c3\u03b7\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n<\/div>\n\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"claims\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--right\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Online-Claim-page-banner-CPs2X8JYmS8-unsplash.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t\u03a0\u0395\u0399\u03a4\u0395 \u039c\u0391\u03a3<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\t\u03a7\u03c1\u03b5\u03b9\u03ac\u03b6\u03b5\u03c4\u03b1\u03b9 \u03bd\u03b1 \u03b1\u03bd\u03b1\u03c6\u03ad\u03c1\u03b5\u03c4\u03b5 \u03ba\u03ac\u03c0\u03bf\u03b9\u03bf \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1;<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u03a4\u03b1 \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd\u03c4\u03b1 Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03c3\u03c7\u03b5\u03b4\u03b9\u03b1\u03c3\u03bc\u03ad\u03bd\u03b1 \u03ba\u03b1\u03b9 \u03ba\u03b1\u03c4\u03b1\u03c3\u03ba\u03b5\u03c5\u03b1\u03c3\u03bc\u03ad\u03bd\u03b1 \u03ad\u03c4\u03c3\u03b9 \u03ce\u03c3\u03c4\u03b5 \u03bd\u03b1 \u03b5\u03af\u03bd\u03b1\u03b9 \u03b1\u03be\u03b9\u03cc\u03c0\u03b9\u03c3\u03c4\u03b1 \u03ba\u03b1\u03b9 \u03b1\u03bd\u03b8\u03b5\u03ba\u03c4\u03b9\u03ba\u03ac \u03c3\u03c4\u03bf \u03c7\u03c1\u03cc\u03bd\u03bf. \u0395\u03ac\u03bd \u03b1\u03bd\u03c4\u03b9\u03bc\u03b5\u03c4\u03c9\u03c0\u03af\u03b6\u03b5\u03c4\u03b5 \u03ba\u03ac\u03c0\u03bf\u03b9\u03bf \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1 \u03bc\u03b5 \u03c4\u03bf \u03c0\u03c1\u03bf\u03ca\u03cc\u03bd \u03c3\u03b1\u03c2, \u03ba\u03ac\u03bd\u03c4\u03b5 \u03ba\u03bb\u03b9\u03ba \u03c0\u03ac\u03bd\u03c9 \u03c3\u03b5 \u03ad\u03bd\u03b1 \u03b1\u03c0\u03cc \u03c4\u03b1 \u03c0\u03b1\u03c1\u03b1\u03ba\u03ac\u03c4\u03c9 \u03c0\u03b5\u03b4\u03af\u03b1 \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03bb\u03ac\u03b2\u03b5\u03c4\u03b5 \u03c5\u03c0\u03bf\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7.\u00a0<br><br>\u03a7\u03c1\u03b7\u03c3\u03b9\u03bc\u03bf\u03c0\u03bf\u03b9\u03ae\u03c3\u03c4\u03b5 \u03c4\u03bf \u03c0\u03c1\u03ce\u03c4\u03bf \u03c0\u03b5\u03b4\u03af\u03bf \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03bb\u03ad\u03be\u03b5\u03c4\u03b5 \u03c4\u03b7\u03bd \u03c4\u03bf\u03c0\u03bf\u03b8\u03b5\u03c3\u03af\u03b1 \u03c3\u03b1\u03c2 \u03ba\u03b1\u03b9 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03b5\u03c4\u03b5 \u03bc\u03b5 \u03c4\u03b7\u03bd \u03c4\u03bf\u03c0\u03b9\u03ba\u03ae \u03bf\u03bc\u03ac\u03b4\u03b1 \u03b5\u03be\u03c5\u03c0\u03b7\u03c1\u03ad\u03c4\u03b7\u03c3\u03b7\u03c2 Solplanet, \u03ae \u03ba\u03ac\u03bd\u03c4\u03b5 \u03ba\u03bb\u03b9\u03ba \u03c3\u03c4\u03bf \u03b4\u03b5\u03cd\u03c4\u03b5\u03c1\u03bf \u03c0\u03b5\u03b4\u03af\u03bf \u03b3\u03b9\u03b1 \u03bd\u03b1 \u03c5\u03c0\u03bf\u03b2\u03ac\u03bb\u03bb\u03b5\u03c4\u03b5 \u03ba\u03ac\u03c0\u03bf\u03b9\u03b1 \u03b1\u03af\u03c4\u03b7\u03c3\u03b7 \u03b1\u03bd\u03c4\u03b9\u03ba\u03b1\u03c4\u03ac\u03c3\u03c4\u03b1\u03c3\u03b7\u03c2 \u03c3\u03c4\u03b7\u03bd \u03bc\u03b7\u03c4\u03c1\u03b9\u03ba\u03ae \u03bc\u03b1\u03c2 \u03b5\u03c4\u03b1\u03b9\u03c1\u03b5\u03af\u03b1, \u03c4\u03b7\u03bd AISWEI.<\/p>\t<\/div>\n\n\n<div class=\"wrapper  wrapper__spacing-top-large--10 wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"https:\/\/onlineclaim-solplanet.aiswei-tech.com\/#\/en\/OnlineClaim\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_selectcountry \" id=\"\" title=\"\u0391\u03bd\u03b1\u03c6\u03ad\u03c1\u03c9 \u03ad\u03bd\u03b1 \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1\" aria-label=\"\">\n\t\t\t\u0391\u03bd\u03b1\u03c6\u03ad\u03c1\u03c9 \u03ad\u03bd\u03b1 \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0  wrapper__divider-top-large\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"contact-us\"><\/div>\n\t\t\t<div class=\"wrapper__container  wrapper__gutter-large--none\">\n\t\t\t<div class=\"wrapper__inner wrapper__width-large--12\">\n\t\t\t\t\n<div class=\"block-card-list block-card-list__media-position--left\">\n\n\t\t\t<div class=\"block-card-list__media\">\n\t\t\t<div class=\"block-card-list__media-inner\">\n\t\t\t\t<div style=\"background-image:url(https:\/\/solplanet.net\/wp-content\/uploads\/2020\/09\/Image-component.jpg)\" class=\"image-bg block-card-list__image-bg\"><\/div>\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t<div class=\"block-card-list__content\">\n\t\t<div class=\"block-card-list__content-inner\">\n\t\t\t\n<div class=\"wrapper   wrapper__spacing-bottom-large--20\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--small block-paragraph__paragraph\">\n\t\u0395\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03b1\u03c0\u03b5\u03c5\u03b8\u03b5\u03af\u03b1\u03c2 \u03bc\u03b1\u03b6\u03af \u03bc\u03b1\u03c2\u00a0<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--40\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t\n<div class=\"block-heading\">\n\t<h2 class=\"heading heading__align--left heading__color--sunsetToDodger heading__size--default block-heading__heading heading__color--is-gradient\">\n\tH Solplanet \u03b5\u03af\u03bd\u03b1\u03b9 \u03bc\u03cc\u03bd\u03bf \u03ad\u03bd\u03b1 \u03c4\u03b7\u03bb\u03b5\u03c6\u03ce\u03bd\u03b7\u03bc\u03b1 \u03ae \u03ad\u03bd\u03b1 \u03ba\u03bb\u03b9\u03ba\u00a0\u03bc\u03b1\u03ba\u03c1\u03b9\u03ac<\/h2>\t<\/div>\n\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--110\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<p class=\"paragraph paragraph__color--dove paragraph__align--left paragraph__size--default block-paragraph__paragraph\">\n\t\u039f \u03ae\u03bb\u03b9\u03bf\u03c2 \u03b4\u03b5\u03bd \u03ba\u03bf\u03b9\u03bc\u03ac\u03c4\u03b1\u03b9 \u03c0\u03c1\u03b1\u03b3\u03bc\u03b1\u03c4\u03b9\u03ba\u03ac \u03c0\u03bf\u03c4\u03ad, \u03bf\u03cd\u03c4\u03b5 \u03ba\u03b9 \u03b5\u03bc\u03b5\u03af\u03c2. \u0391\u03bd \u03ad\u03c7\u03b5\u03c4\u03b5 \u03ba\u03ac\u03c0\u03bf\u03b9\u03bf \u03b5\u03c0\u03b5\u03af\u03b3\u03bf\u03bd \u03c0\u03c1\u03cc\u03b2\u03bb\u03b7\u03bc\u03b1 \u03ae \u03b5\u03c0\u03af\u03bc\u03bf\u03bd\u03bf \u03b8\u03ad\u03bc\u03b1 \u03bc\u03b5 \u03c4\u03bf \u03bf\u03c0\u03bf\u03af\u03bf \u03c7\u03c1\u03b5\u03b9\u03ac\u03b6\u03b5\u03c3\u03c4\u03b5 \u03b2\u03bf\u03ae\u03b8\u03b5\u03b9\u03b1, \u03bc\u03b7 \u03b4\u03b9\u03c3\u03c4\u03ac\u03c3\u03b5\u03c4\u03b5 \u03bd\u03b1 \u03b5\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03b5\u03c4\u03b5 \u03bc\u03b5 \u03c4\u03b7\u03bd \u03bf\u03bc\u03ac\u03b4\u03b1 Solplanet \u03c4\u03b7\u03c2 \u03c0\u03b5\u03c1\u03b9\u03bf\u03c7\u03ae\u03c2 \u03c3\u03b1\u03c2 \u03b3\u03b9\u03b1 \u03b3\u03c1\u03ae\u03b3\u03bf\u03c1\u03b7 \u03c5\u03c0\u03bf\u03c3\u03c4\u03ae\u03c1\u03b9\u03be\u03b7.<\/p>\t<\/div>\n\n\n<div class=\"wrapper   wrapper__spacing-bottom-large--0\" id=\"\">\n\t<div class=\"wrapper__anchor\" id=\"\"><\/div>\n\t\t\t<div class=\"btn__wrap btn__align--left block-button__btn\">\n\t\t\t<a href=\"\/el\/contact-us\/\" class=\"btn btn__color--alto btn__size--default btn__size-width--default     gtm_contactus \" id=\"\" title=\"\u0395\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03bc\u03b1\u03b6\u03af \u03bc\u03b1\u03c2\" aria-label=\"\">\n\t\t\t\u0395\u03c0\u03b9\u03ba\u03bf\u03b9\u03bd\u03c9\u03bd\u03ae\u03c3\u03c4\u03b5 \u03bc\u03b1\u03b6\u03af \u03bc\u03b1\u03c2\t\t<\/a>\n\t<\/div>\t<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Installer Area | Solplanet<\/title>\n<meta name=\"description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/solplanet.net\/el\/installer-area\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Installer Area | Solplanet\" \/>\n<meta property=\"og:description\" content=\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/solplanet.net\/el\/installer-area\" \/>\n<meta property=\"og:site_name\" content=\"Solplanet\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T13:44:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/solplanet.net\/el\/installer-area\",\"url\":\"https:\/\/solplanet.net\/el\/installer-area\",\"name\":\"Installer Area | Solplanet\",\"isPartOf\":{\"@id\":\"https:\/\/solplanet.net\/el#website\"},\"datePublished\":\"2020-09-15T11:54:17+00:00\",\"dateModified\":\"2024-06-04T13:44:07+00:00\",\"description\":\"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.\",\"breadcrumb\":{\"@id\":\"https:\/\/solplanet.net\/el\/installer-area#breadcrumb\"},\"inLanguage\":\"el\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/solplanet.net\/el\/installer-area\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/solplanet.net\/el\/installer-area#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/solplanet.net\/el\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Installer Area\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/solplanet.net\/el#website\",\"url\":\"https:\/\/solplanet.net\/el\",\"name\":\"Solplanet\",\"description\":\"Solar for everybody\",\"publisher\":{\"@id\":\"https:\/\/solplanet.net\/el#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/solplanet.net\/el?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/solplanet.net\/el#organization\",\"name\":\"Solplanet\",\"url\":\"https:\/\/solplanet.net\/el\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\/\/solplanet.net\/el#\/schema\/logo\/image\/\",\"url\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"contentUrl\":\"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg\",\"width\":500,\"height\":500,\"caption\":\"Solplanet\"},\"image\":{\"@id\":\"https:\/\/solplanet.net\/el#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Installer Area | Solplanet","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/solplanet.net\/el\/installer-area","og_locale":"el_GR","og_type":"article","og_title":"Installer Area | Solplanet","og_description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","og_url":"https:\/\/solplanet.net\/el\/installer-area","og_site_name":"Solplanet","article_modified_time":"2024-06-04T13:44:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/solplanet.net\/el\/installer-area","url":"https:\/\/solplanet.net\/el\/installer-area","name":"Installer Area | Solplanet","isPartOf":{"@id":"https:\/\/solplanet.net\/el#website"},"datePublished":"2020-09-15T11:54:17+00:00","dateModified":"2024-06-04T13:44:07+00:00","description":"The power of the sun is the future of our planet. Solplanet makes solar for everybody. Easy-to-install, reliable and user-friendly inverters.","breadcrumb":{"@id":"https:\/\/solplanet.net\/el\/installer-area#breadcrumb"},"inLanguage":"el","potentialAction":[{"@type":"ReadAction","target":["https:\/\/solplanet.net\/el\/installer-area"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/solplanet.net\/el\/installer-area#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/solplanet.net\/el"},{"@type":"ListItem","position":2,"name":"Installer Area"}]},{"@type":"WebSite","@id":"https:\/\/solplanet.net\/el#website","url":"https:\/\/solplanet.net\/el","name":"Solplanet","description":"Solar for everybody","publisher":{"@id":"https:\/\/solplanet.net\/el#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/solplanet.net\/el?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/solplanet.net\/el#organization","name":"Solplanet","url":"https:\/\/solplanet.net\/el","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/solplanet.net\/el#\/schema\/logo\/image\/","url":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","contentUrl":"https:\/\/solplanet.net\/wp-content\/uploads\/2020\/11\/Solplanet-LinkedInIcon.jpg","width":500,"height":500,"caption":"Solplanet"},"image":{"@id":"https:\/\/solplanet.net\/el#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/pages\/110484"}],"collection":[{"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/comments?post=110484"}],"version-history":[{"count":10,"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/pages\/110484\/revisions"}],"predecessor-version":[{"id":135852,"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/pages\/110484\/revisions\/135852"}],"wp:attachment":[{"href":"https:\/\/solplanet.net\/el\/wp-json\/wp\/v2\/media?parent=110484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}